{"id":6090,"date":"2024-05-03T06:31:26","date_gmt":"2024-05-03T06:31:26","guid":{"rendered":"https:\/\/elfsight.com\/pt\/?page_id=6090"},"modified":"2025-03-05T06:36:27","modified_gmt":"2025-03-05T06:36:27","slug":"google-sites","status":"publish","type":"page","link":"https:\/\/elfsight.com\/pt\/button-widget\/google-sites\/","title":{"rendered":"Button &#8211; Google Sites"},"content":{"rendered":"\n<div class=\"application-platform-content-item-description application-platform-content-item\" id=\"description\" data-nav-section=\"description\"> <h2>Incorporar bot\u00e3o no Google Sites com o widget Elfsight<\/h2> <p>O Elfsight Button \u00e9 um plugin para Google Sites que permite fazer v\u00e1rios bot\u00f5es para v\u00e1rios objetivos em seu site. Existem muitas a\u00e7\u00f5es que podem ser realizadas depois que o visitante do site clica no bot\u00e3o. Por exemplo, eles podem ser enviados para algum site de terceiros, discar seu n\u00famero de telefone, conversar por meio de um mensageiro conhecido e muito mais. O bot\u00e3o \u00e9 altamente personaliz\u00e1vel &#8211; voc\u00ea pode usar qualquer texto e conte\u00fado ao redor do bot\u00e3o e ajustar seu tamanho e cores. <\/p> <p><b>Use um bot\u00e3o atraente para aumentar as vendas em seu site, atrair mais assinantes nas redes sociais e muito mais! <\/b><\/p> <\/div> <div class=\"application-platform-content-item-features application-platform-content-item\" id=\"features\" data-nav-section=\"features\"> <h2>Confira a lista dos recursos mais importantes: <\/h2> <ul><li>Alterar cores e fontes<\/li> <li>Dois tipos de posicionamento de bot\u00e3o &#8211; Incorporado e Flutuante<\/li><li>Uma possibilidade de adicionar conte\u00fado acima e abaixo do bot\u00e3o<\/li><li>Um r\u00f3tulo que pode ter duas linhas<\/li><li>Acima 8 varia\u00e7\u00f5es de cen\u00e1rios ap\u00f3s um clique<\/li><\/ul><p><a href=\"#demo\">Voc\u00ea pode verificar o que o plugin oferece usando a demonstra\u00e7\u00e3o<\/a><\/p> <\/div> <div class=\"application-platform-content-item-installation application-platform-content-item\" id=\"installation\" data-nav-section=\"installation\"> <h2>Como adiciono um bot\u00e3o ao meu site do Google Sites? <\/h2> <p>Basta seguir as orienta\u00e7\u00f5es abaixo para inserir a ferramenta. <\/p> <ol><li><b>Use nosso configurador gratuito e comece a construir seu pr\u00f3prio plugin. <\/b><br> Encontre a interface e os par\u00e2metros preferidos da ferramenta e salve as modifica\u00e7\u00f5es. <\/li> <li><b>Receba seu c\u00f3digo exclusivo exposto na janela dos aplicativos Elfsight. <\/b><br> Ap\u00f3s a conclus\u00e3o da personaliza\u00e7\u00e3o do seu widget, copie o c\u00f3digo pessoal da janela exibida e salve-o para uso posterior. <\/li> <li><b>Comece a usar o plug-in no seu site do Google Sites. <\/b><br> Insira o c\u00f3digo copiado anteriormente em sua p\u00e1gina e aplique as edi\u00e7\u00f5es. <\/li> <li><b>Conclu\u00eddo! A integra\u00e7\u00e3o foi finalizada com sucesso. <\/b><br> Acesse seu site para ver como a ferramenta funciona. <\/li><\/ol> <div class=\"tip-yellow tip\"><b>Devido \u00e0s peculiaridades do funcionamento do Google Sites, o widget pode ter uma apar\u00eancia diferente da demonstra\u00e7\u00e3o on-line. Pedimos desculpas por qualquer inconveniente causado.<\/b><\/div><p>Caso tenha d\u00favidas ou encontre alguma dificuldade, entre em contato com nossa equipe de suporte. Nosso pessoal deseja ajud\u00e1-lo com todos os problemas que voc\u00ea possa ter com o plugin. <\/p> <div class=\"faq\" data-component=\"FAQ\"><div class=\"faq-item\">\n\t\t\t\t\t<div class=\"faq-item-question\">\n\t\t\t\t\t\t<h3 class=\"faq-item-question-text\">Como posso adicionar o Button ao meu site do Google Sites sem conhecimentos de codifica\u00e7\u00e3o?<\/h3>\n\n\t\t\t\t\t\t<div class=\"faq-item-question-icon\"><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"faq-item-answer\">\n\t\t\t\t\t\t<div class=\"faq-item-answer-text\"> <p>A Elfsight fornece uma solu\u00e7\u00e3o SaaS que permite criar voc\u00ea mesmo um widget de Button. Veja como \u00e9 f\u00e1cil o processo \u00e9: Trabalhe diretamente no Editor on-line para criar um widget de bot\u00e3o que voc\u00ea gostaria de ver em seu site do Google Sites. Escolha um dos modelos predefinidos e ajuste as configura\u00e7\u00f5es do bot\u00e3o, adicione seu conte\u00fado, altere o layout e as cores sem nenhuma habilidade de codifica\u00e7\u00e3o. Salve o bot\u00e3o e copie seu c\u00f3digo de instala\u00e7\u00e3o, que voc\u00ea pode incluir facilmente em seu site do Google Sites, sem a necessidade de adquirir uma assinatura paga. Com nosso editor intuitivo, qualquer usu\u00e1rio da Internet pode criar um widget de bot\u00e3o on-line e incorpor\u00e1-lo facilmente ao site do Google Sites. N\u00e3o h\u00e1 necessidade de pagar ou inserir as credenciais do seu cart\u00e3o para acessar o servi\u00e7o. Se voc\u00ea enfrentar qualquer problema em qualquer etapa, n\u00e3o hesite em entrar em contato com nossa equipe de suporte t\u00e9cnico.<\/p> <\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div> <\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":0,"parent":1384,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-application-platform.php","meta":{"publish_to_discourse":"","publish_post_category":"","wpdc_auto_publish_overridden":"","wpdc_topic_tags":"","wpdc_pin_topic":"","wpdc_pin_until":"","discourse_post_id":"","discourse_permalink":"","wpdc_publishing_response":"","wpdc_publishing_error":"","footnotes":""},"class_list":["post-6090","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Widget de plug-in de bot\u00e3o - Adicionar plug-in de bot\u00e3o ao Google Sites (2026)<\/title>\n<meta name=\"description\" content=\"Teste o plugin Elfsight Button para Google Sites. Obtenha novos assinantes, aumente as vendas e fa\u00e7a com que o seu neg\u00f3cio seja um sucesso aplicando as ferramentas da Elfsight!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elfsight.com\/pt\/button-widget\/google-sites\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Widget de plug-in de bot\u00e3o - Adicionar plug-in de bot\u00e3o ao Google Sites (2026)\" \/>\n<meta property=\"og:description\" content=\"Teste o plugin Elfsight Button para Google Sites. Obtenha novos assinantes, aumente as vendas e fa\u00e7a com que o seu neg\u00f3cio seja um sucesso aplicando as ferramentas da Elfsight!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elfsight.com\/pt\/button-widget\/google-sites\/\" \/>\n<meta property=\"og:site_name\" content=\"Elfsight PT\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-05T06:36:27+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Widget de plug-in de bot\u00e3o - Adicionar plug-in de bot\u00e3o ao Google Sites (2026)","description":"Teste o plugin Elfsight Button para Google Sites. Obtenha novos assinantes, aumente as vendas e fa\u00e7a com que o seu neg\u00f3cio seja um sucesso aplicando as ferramentas da Elfsight!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elfsight.com\/pt\/button-widget\/google-sites\/","og_locale":"pt_PT","og_type":"article","og_title":"Widget de plug-in de bot\u00e3o - Adicionar plug-in de bot\u00e3o ao Google Sites (2026)","og_description":"Teste o plugin Elfsight Button para Google Sites. Obtenha novos assinantes, aumente as vendas e fa\u00e7a com que o seu neg\u00f3cio seja um sucesso aplicando as ferramentas da Elfsight!","og_url":"https:\/\/elfsight.com\/pt\/button-widget\/google-sites\/","og_site_name":"Elfsight PT","article_modified_time":"2025-03-05T06:36:27+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elfsight.com\/pt\/button-widget\/google-sites\/","url":"https:\/\/elfsight.com\/pt\/button-widget\/google-sites\/","name":"Widget de plug-in de bot\u00e3o - Adicionar plug-in de bot\u00e3o ao Google Sites (2026)","isPartOf":{"@id":"https:\/\/elfsight.com\/pt\/#website"},"datePublished":"2024-05-03T06:31:26+00:00","dateModified":"2025-03-05T06:36:27+00:00","description":"Teste o plugin Elfsight Button para Google Sites. Obtenha novos assinantes, aumente as vendas e fa\u00e7a com que o seu neg\u00f3cio seja um sucesso aplicando as ferramentas da Elfsight!","breadcrumb":{"@id":"https:\/\/elfsight.com\/pt\/button-widget\/google-sites\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elfsight.com\/pt\/button-widget\/google-sites\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/elfsight.com\/pt\/button-widget\/google-sites\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elfsight.com\/pt\/"},{"@type":"ListItem","position":2,"name":"Button","item":"https:\/\/elfsight.com\/pt\/button-widget\/"},{"@type":"ListItem","position":3,"name":"Button &#8211; Google Sites"}]},{"@type":"WebSite","@id":"https:\/\/elfsight.com\/pt\/#website","url":"https:\/\/elfsight.com\/pt\/","name":"Elfsight PT","description":"Just another Elfsight Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elfsight.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"meta_box":{"industry":"","seo_heading":"","heading":"","description":"","cta_heading":"","cta_description":"","application":"1383","h1":"Plug-in de bot\u00e3o do Google Sites","h1_caption":"Empurre seus visitantes direto para a a\u00e7\u00e3o","application_category":[],"applications_title":"","applications_request_title":"","applications_request_button_text":"","hero_text":"","hero_video":"","hero_video_schema_markup":"","selling_points_title":"","selling_points_caption":"","selling_points":[],"selling_points_cta_text":"","features_title":"","features":"","ed_cta_examples_text":"","ed_cta_examples_hidden":"","ed_cta_demo_text":"","ed_cta_demo_hidden":"","why_caption":"","why_editor_title":"","why_editor_text":"","why_team_title":"","why_team_text":"","why_service_title":"","why_service_text":"","template_catalog_visible":"0","template_catalog_title":"","template_catalog_text":"","template_catalog_categories_visible":"","demo_title":"Crie seu widget de bot\u00e3o","demo_caption":"Configure seu bot\u00e3o e adicione-o ao seu site do Google Sites gratuitamente!","default_faq_hidden":"","app_template_category":[],"platform":"112","template_public_id":"","codecanyon_url":"","codecanyon_item_id":"","codecanyon_price":"","pricing_caption":"","pricing_elfsight_apps_hide_column":"","pricing_elfsight_apps_url":"","pricing_codecanyon_price_caption":"","integration_category":[],"integration_request_title":"","integration_request_cta":"","integration_platform":"","integrations":[],"platform_category":[],"video_schema_markup":"","price":"a partir de US$ 0\/m\u00eas","trial":"","benefits":[{"text":"Servi\u00e7o de instala\u00e7\u00e3o gratuito"},{"text":"Atendimento ao cliente profissional"},{"text":"Garantia de reembolso de 14 dias"},{"text":"Melhorias futuras"}],"button_url":"#demo","button_target_blank":"0","button_nofollow":"0","attributes":[{"name":"Instala\u00e7\u00f5es","content":"10,000 - 100,000"},{"name":"Responsivo","content":"Sim"},{"name":"Navegadores compat\u00edveis","content":"Firefox, Safari, Opera, Chrome, Edge"}],"tags":[],"tags_disable_links":"0","hide_more_platforms":"0","video_object":"","demo_hide_cta":"0","demo_hide_cloud_options":"0","pricing_title":"","pricing":[{"pricing_icon":"platform","pricing_title":"Elfsight Apps","pricing_title_caption":"Vers\u00e3o multiplataforma","pricing_price":"a partir de US$ 0\/m\u00eas","pricing_price_caption":"comece com um plano gratuito","pricing_benefits":[{"text":"Dom\u00ednios ilimitados"},{"text":"Suporte profissional e pontual"},{"text":"Suporte profissional e pontual"},{"text":"Design flex\u00edvel"}],"pricing_button_text":"Adicionar ao site","pricing_button_url":"#demo"}],"related_apps_title":"","related_apps_hidden":"0","author":"","image":[],"title":"","job":"","social_networks":[]},"_links":{"self":[{"href":"https:\/\/elfsight.com\/pt\/wp-json\/wp\/v2\/pages\/6090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elfsight.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/elfsight.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/elfsight.com\/pt\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/elfsight.com\/pt\/wp-json\/wp\/v2\/comments?post=6090"}],"version-history":[{"count":3,"href":"https:\/\/elfsight.com\/pt\/wp-json\/wp\/v2\/pages\/6090\/revisions"}],"predecessor-version":[{"id":14388,"href":"https:\/\/elfsight.com\/pt\/wp-json\/wp\/v2\/pages\/6090\/revisions\/14388"}],"up":[{"embeddable":true,"href":"https:\/\/elfsight.com\/pt\/wp-json\/wp\/v2\/pages\/1384"}],"wp:attachment":[{"href":"https:\/\/elfsight.com\/pt\/wp-json\/wp\/v2\/media?parent=6090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}