{"id":6459,"date":"1970-01-01T00:00:00","date_gmt":"1970-01-01T00:00:00","guid":{"rendered":"https:\/\/elfsight.com\/it\/?page_id=6459"},"modified":"2025-03-21T04:04:58","modified_gmt":"2025-03-21T04:04:58","slug":"webnode","status":"publish","type":"page","link":"https:\/\/elfsight.com\/it\/viber-chat-widget\/webnode\/","title":{"rendered":"Viber Chat &#8211; Webnode"},"content":{"rendered":"\n<div class=\"application-platform-content-item-description application-platform-content-item\" id=\"description\" data-nav-section=\"description\"> <h2>Descrizione<\/h2><p>Elfsight Viber Chat \u00e8 la possibilit\u00e0 pi\u00f9 veloce per le persone di contattarti rimanendo sul tuo sito web. Ogni utente ricever\u00e0 rapidamente soluzioni alle sue domande o supporto da te. Rimani disponibile online in uno dei messenger pi\u00f9 utilizzati. Puoi scegliere che la chat di Elfsight Viber si verifichi su pagine particolari e indirizzarla a categorie separate di pubblico. Esistono ampie possibilit\u00e0 di personalizzazione: scegli i trigger di avvio della chat, componi il testo di benvenuto, scegli le icone e molto altro. Utilizzando Viber Chat sul sito web rimarrai raggiungibile per le persone in ogni momento e in qualsiasi luogo.<\/p><p><b>Aggiungi Viber Chat per raggiungere i picchi di business con meno sforzo!<\/b><\/p> <\/div> <div class=\"application-platform-content-item-features application-platform-content-item\" id=\"features\" data-nav-section=\"features\"> <h2>Ecco le caratteristiche fondamentali del widget:<\/h2><ul><li>Una raccolta di icone a bolle tra cui scegliere<\/li><li>Testo a bolle modificabile <\/li><li>Intestazione FlexibleChat con logo della pagina, nome e didascalia<\/li><li>Nome della chat modificabile<\/li><li>Impostazione di testo personalizzato come didascalia della chat<\/li><li>Pulsante Avvia chat con testo modificabile<\/li><\/ul><p><a href=\"#demo\">Prova tutte le impostazioni nella demo completa<\/a><\/p><\/div> <div class=\"application-platform-content-item-installation application-platform-content-item\" id=\"installation\" data-nav-section=\"installation\"> <h2>Come posso aggiungere Viber Chat al mio Webnode?<\/h2><p>Basta applicare le istruzioni seguenti per incorporare lo strumento.<\/p><ol><li><b>Lancio la nostra demo gratuita e inizia a costruire il tuo strumento.<\/b><br>Trova l&#8217;interfaccia e le opzioni preferibili dello strumento e applica le modifiche.<\/li><li><b>Acquisisci il tuo codice individuale che appare nella vedova delle app Elfsight<\/b><br>Subito dopo aver terminato la creazione del plugin, copia il codice personale dal popup emerso e conservalo per un uso successivo.<\/li><li><b>Avvia l&#8217;utilizzo del plugin sul tuo sito Webnode pagina<\/b><br>Implementa il codice che hai salvato di recente nel tuo sito web e applica le correzioni.<\/li><li><b>Il gioco \u00e8 fatto! L&#8217;incorporamento \u00e8 terminato con successo<\/b><br>Vai sul tuo sito per controllare come funziona il plugin.<\/li><\/ol><p>A condizione di affrontare domande o affrontare alcuni problemi, sentiti libero di fare appello al nostro supporto personale. I nostri consulenti non vedono l&#8217;ora di risolvere tutti i problemi che potresti avere con il plugin.<\/p><div class=\"faq\" data-component=\"FAQ\"> <div class=\"faq-item\">\n\t\t\t\t\t<div class=\"faq-item-question\">\n\t\t\t\t\t\t<h3 class=\"faq-item-question-text\">Come aggiungere Viber Chat al mio sito Webnode senza competenze di programmazione?<\/h3>\n\n\t\t\t\t\t\t<div class=\"faq-item-question-icon\"><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"faq-item-answer\">\n\t\t\t\t\t\t<div class=\"faq-item-answer-text\"> <p>Elfsight fornisce un servizio SaaS soluzione che ti consente di creare tu stesso un widget Viber Chat, scopri quanto \u00e8 semplice il processo: lavora direttamente nell&#8217;editor online per creare un widget Viber Chat che vorresti vedere sul tuo sito Webnode. Scegli uno dei modelli predefiniti e regola le impostazioni di Viber Chat, aggiungi i tuoi contenuti, modifica il layout e i colori senza alcuna abilit\u00e0 di codifica. Salva la chat di Viber e copia il codice di installazione, che potrai facilmente incorporare nel tuo sito Webnode senza dover acquistare una versione a pagamento. Con il nostro editor intuitivo qualsiasi utente di Internet pu\u00f2 creare widget Viber Chat online e incorporarlo facilmente nel proprio sito Webnode. Non \u00e8 necessario pagare o inserire le credenziali della carta per accedere al servizio. In caso di problemi in qualsiasi momento, non esitate a contattare il nostro team di supporto tecnico.<\/p> <\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div> <\/div> <\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":0,"parent":2950,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-application-platform.php","meta":{"publish_to_discourse":"","publish_post_category":"","wpdc_auto_publish_overridden":"","wpdc_topic_tags":"","wpdc_pin_topic":"","wpdc_pin_until":"","discourse_post_id":"","discourse_permalink":"","wpdc_publishing_response":"","wpdc_publishing_error":"","footnotes":""},"class_list":["post-6459","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aggiungi Viber Chat al sito web Webnode senza codifica (2026)<\/title>\n<meta name=\"description\" content=\"Aggiungi Viber Chat al sito per una comunicazione fluida e istantanea con gli utenti. Dai un&#039;occhiata a Elfsight freedemo per creare subito il tuo plugin unico.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elfsight.com\/it\/viber-chat-widget\/webnode\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aggiungi Viber Chat al sito web Webnode senza codifica (2026)\" \/>\n<meta property=\"og:description\" content=\"Aggiungi Viber Chat al sito per una comunicazione fluida e istantanea con gli utenti. Dai un&#039;occhiata a Elfsight freedemo per creare subito il tuo plugin unico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elfsight.com\/it\/viber-chat-widget\/webnode\/\" \/>\n<meta property=\"og:site_name\" content=\"Elfsight IT\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-21T04:04:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aggiungi Viber Chat al sito web Webnode senza codifica (2026)","description":"Aggiungi Viber Chat al sito per una comunicazione fluida e istantanea con gli utenti. Dai un'occhiata a Elfsight freedemo per creare subito il tuo plugin unico.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elfsight.com\/it\/viber-chat-widget\/webnode\/","og_locale":"it_IT","og_type":"article","og_title":"Aggiungi Viber Chat al sito web Webnode senza codifica (2026)","og_description":"Aggiungi Viber Chat al sito per una comunicazione fluida e istantanea con gli utenti. Dai un'occhiata a Elfsight freedemo per creare subito il tuo plugin unico.","og_url":"https:\/\/elfsight.com\/it\/viber-chat-widget\/webnode\/","og_site_name":"Elfsight IT","article_modified_time":"2025-03-21T04:04:58+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elfsight.com\/it\/viber-chat-widget\/webnode\/","url":"https:\/\/elfsight.com\/it\/viber-chat-widget\/webnode\/","name":"Aggiungi Viber Chat al sito web Webnode senza codifica (2026)","isPartOf":{"@id":"https:\/\/elfsight.com\/it\/#website"},"datePublished":"1970-01-01T00:00:00+00:00","dateModified":"2025-03-21T04:04:58+00:00","description":"Aggiungi Viber Chat al sito per una comunicazione fluida e istantanea con gli utenti. Dai un'occhiata a Elfsight freedemo per creare subito il tuo plugin unico.","breadcrumb":{"@id":"https:\/\/elfsight.com\/it\/viber-chat-widget\/webnode\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elfsight.com\/it\/viber-chat-widget\/webnode\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/elfsight.com\/it\/viber-chat-widget\/webnode\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elfsight.com\/it\/"},{"@type":"ListItem","position":2,"name":"Viber Chat","item":"https:\/\/elfsight.com\/it\/viber-chat-widget\/"},{"@type":"ListItem","position":3,"name":"Viber Chat &#8211; Webnode"}]},{"@type":"WebSite","@id":"https:\/\/elfsight.com\/it\/#website","url":"https:\/\/elfsight.com\/it\/","name":"Elfsight IT","description":"Just another Elfsight Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elfsight.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"meta_box":{"industry":"","seo_heading":"","heading":"","description":"","cta_heading":"","cta_description":"","application":"2949","h1":"Webnode ViberChat","h1_caption":"Offri Viber come canale di comunicazione sul tuo sito web, consentendo ai visitatori di raggiungere facilmente il tuo sito Webnode.","application_category":[],"applications_title":"","applications_request_title":"","applications_request_button_text":"","hero_text":"","hero_video":"","hero_video_schema_markup":"","selling_points_title":"","selling_points_caption":"","selling_points":[],"selling_points_cta_text":"","features_title":"","features":"","ed_cta_examples_text":"","ed_cta_examples_hidden":"","ed_cta_demo_text":"","ed_cta_demo_hidden":"","why_caption":"","why_editor_title":"","why_editor_text":"","why_team_title":"","why_team_text":"","why_service_title":"","why_service_text":"","template_catalog_visible":"0","template_catalog_title":"","template_catalog_text":"","template_catalog_categories_visible":"","demo_title":"Crea il tuo widget Viber Chat","demo_caption":"Configura la tua chat Viber e aggiungila gratuitamente al tuo sito Webnode!","default_faq_hidden":"","app_template_category":[],"platform":"47","template_public_id":"","codecanyon_url":"","codecanyon_item_id":"","codecanyon_price":"","pricing_caption":"","pricing_elfsight_apps_hide_column":"","pricing_elfsight_apps_url":"","pricing_codecanyon_price_caption":"","integration_category":[],"integration_request_title":"","integration_request_cta":"","integration_platform":"","integrations":[],"platform_category":[],"video_schema_markup":"","price":"da $ 0 al mese","trial":"","benefits":[{"text":"Assistenza per l'installazione gratuita"},{"text":"Servizio clienti professionale"},{"text":"Garanzia di rimborso di 14 giorni"},{"text":"Miglioramenti gratuiti a vita"}],"button_url":"#demo","button_target_blank":"0","button_nofollow":"0","attributes":[{"name":"Installazioni"},{"name":"Reattivo"},{"name":"Browser compatibili"}],"tags":[],"tags_disable_links":"0","hide_more_platforms":"0","video_object":"","demo_hide_cta":"0","demo_hide_cloud_options":"0","pricing_title":"","pricing":[{"pricing_icon":"platform","pricing_title":"Elfsight Apps","pricing_title_caption":"Versione multipiattaforma adatta a qualsiasi sito web","pricing_price":"da $ 0 \/ mese","pricing_price_caption":"inizia con il piano gratuito","pricing_benefits":[{"text":"Siti web illimitati"},{"text":"Supporto rapido e ben documentato"},{"text":"Aiuto gratuito per l'installazione"},{"text":"Prezzo speciale per pi\u00f9 app"}],"pricing_button_text":"Aggiungi al sito web","pricing_button_url":"#demo"}],"related_apps_title":"","related_apps_hidden":"0","author":"","image":[],"title":"","job":"","social_networks":[]},"_links":{"self":[{"href":"https:\/\/elfsight.com\/it\/wp-json\/wp\/v2\/pages\/6459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elfsight.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/elfsight.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/elfsight.com\/it\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/elfsight.com\/it\/wp-json\/wp\/v2\/comments?post=6459"}],"version-history":[{"count":2,"href":"https:\/\/elfsight.com\/it\/wp-json\/wp\/v2\/pages\/6459\/revisions"}],"predecessor-version":[{"id":9453,"href":"https:\/\/elfsight.com\/it\/wp-json\/wp\/v2\/pages\/6459\/revisions\/9453"}],"up":[{"embeddable":true,"href":"https:\/\/elfsight.com\/it\/wp-json\/wp\/v2\/pages\/2950"}],"wp:attachment":[{"href":"https:\/\/elfsight.com\/it\/wp-json\/wp\/v2\/media?parent=6459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}