{"id":9756,"date":"1970-01-01T00:00:00","date_gmt":"1970-01-01T00:00:00","guid":{"rendered":"https:\/\/elfsight.com\/fr\/?page_id=9756"},"modified":"2025-07-10T12:27:37","modified_gmt":"2025-07-10T12:27:37","slug":"drupal","status":"publish","type":"page","link":"https:\/\/elfsight.com\/fr\/podcast-player-widget\/drupal\/","title":{"rendered":"Podcast Player &#8211; Drupal"},"content":{"rendered":"<div class=\"application-platform-content-item-description application-platform-content-item\" id=\"description\" data-nav-section=\"description\"> <h2>Description<\/h2> <p>Elfsight Podcast Player est un module simple pour Drupal qui vous permet de diffuser des podcasts sur les pages de votre site . Le widget est hautement r\u00e9glable\u00a0: vous pouvez modifier son emplacement, le placer n&rsquo;importe o\u00f9 sur la page, redimensionner sa taille, modifier l&rsquo;arri\u00e8re-plan et d&rsquo;autres \u00e9l\u00e9ments pour le combiner avec le style de votre site Web, appliquer une palette de couleurs sombres, d\u00e9montrer des images et d\u00e9montrer ou masquer 3 composants de lecteur suppl\u00e9mentaires, par exemple la barre de progression et autres. Divertissez vos visiteurs, activez l&rsquo;option de lecture automatique et n&rsquo;ayez aucun doute\u00a0: vos utilisateurs ne quitteront pas votre site Web imm\u00e9diatement\u00a0! <\/p> <p><b>Faites plaisir \u00e0 vos utilisateurs en leur offrant du mat\u00e9riel pratique et divertissant gr\u00e2ce \u00e0 Elfsight Podcast Player<\/b><\/p> <\/div> <div class=\"application-platform-content-item-features application-platform-content-item\" id=\"features\" data-nav-section=\"features\"> <h2> Les fonctionnalit\u00e9s les plus demand\u00e9es du module offrent<\/h2> <ul><li>De nombreuses modifications de couleurs. <\/li><li>Deux mises en page pr\u00eates \u00e0 l&#8217;emploi. <\/li><li>Une opportunit\u00e9 d&rsquo;ajouter une image d&rsquo;arri\u00e8re-plan. <\/li><li>Ajoutez un nombre illimit\u00e9 de pistes. <\/li><li>Une option pour cr\u00e9er votre propre palette de couleurs. <\/li><\/ul><p><a href=\"#demo\">Consultez simplement cette d\u00e9mo pour voir ce que vaut le module<\/a><\/p> <\/div> <div class=\"application-platform-content-item-installation application-platform-content-item\" id=\"installation\" data-nav-section=\"installation\"> <h2>Comment ajouter Podcast Player dans ma page web Drupal ? <\/h2><div class=\"video-container\"><iframe width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/A1CRkUJ299A\" frameborder=\"0\" allowfullscreen><\/iframe><\/div><p>Appliquez simplement les instructions ci-dessous pour int\u00e9grer l&rsquo;outil. <\/p> <ol><li><b>Ex\u00e9cutez notre \u00e9diteur gratuit et commencez \u00e0 cr\u00e9er votre module unique. <\/b><br> Retrouvez l&rsquo;apparence personnalis\u00e9e et les options du module et appliquez toutes les corrections. <\/li> <li><b>Obtenez le code individuel affich\u00e9 dans le formulaire sp\u00e9cial sur les applications Elfsight. <\/b><br> D\u00e8s que la cr\u00e9ation de votre module est termin\u00e9e, copiez le code individuel dans la case qui appara\u00eet et enregistrez-le pour une occasion ult\u00e9rieure. <\/li> <li><b>Commencez l&#8217;emploi du module sur le site Drupal. <\/b><br> Int\u00e9grez le code enregistr\u00e9 pr\u00e9c\u00e9demment dans votre page et enregistrez les corrections. <\/li> <li><b>Vous avez termin\u00e9\u00a0! L&rsquo;installation est termin\u00e9e avec succ\u00e8s. <\/b><br> Visitez votre site pour examiner comment fonctionne le module. <\/li><\/ol><p>\u00c0 condition de r\u00e9pondre \u00e0 des demandes de renseignements ou de faire face \u00e0 des probl\u00e8mes, n&rsquo;h\u00e9sitez pas \u00e0 \u00e9crire \u00e0 notre \u00e9quipe du service client. Nos consultants seront ravis de vous aider avec tous les probl\u00e8mes que vous pourriez rencontrer avec le produit. <\/p> <\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":0,"parent":2529,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-application-platform.php","meta":{"publish_to_discourse":"","publish_post_category":"","wpdc_auto_publish_overridden":"","wpdc_topic_tags":"","wpdc_pin_topic":"","wpdc_pin_until":"","discourse_post_id":"","discourse_permalink":"","wpdc_publishing_response":"","wpdc_publishing_error":"","footnotes":""},"class_list":["post-9756","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Elfsight Podcast Player pour le site Drupal (facile et gratuit)<\/title>\n<meta name=\"description\" content=\"Utilisez notre d\u00e9mo pratique et ajoutez un lecteur de podcast r\u00e9actif sur votre page Web Drupal. Utilisez notre d\u00e9mo accessible et cr\u00e9ez votre widget sur mesure en un clic !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elfsight.com\/fr\/podcast-player-widget\/drupal\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elfsight Podcast Player pour le site Drupal (facile et gratuit)\" \/>\n<meta property=\"og:description\" content=\"Utilisez notre d\u00e9mo pratique et ajoutez un lecteur de podcast r\u00e9actif sur votre page Web Drupal. Utilisez notre d\u00e9mo accessible et cr\u00e9ez votre widget sur mesure en un clic !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elfsight.com\/fr\/podcast-player-widget\/drupal\/\" \/>\n<meta property=\"og:site_name\" content=\"Elfsight FR\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-10T12:27:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elfsight Podcast Player pour le site Drupal (facile et gratuit)","description":"Utilisez notre d\u00e9mo pratique et ajoutez un lecteur de podcast r\u00e9actif sur votre page Web Drupal. Utilisez notre d\u00e9mo accessible et cr\u00e9ez votre widget sur mesure en un clic !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elfsight.com\/fr\/podcast-player-widget\/drupal\/","og_locale":"fr_FR","og_type":"article","og_title":"Elfsight Podcast Player pour le site Drupal (facile et gratuit)","og_description":"Utilisez notre d\u00e9mo pratique et ajoutez un lecteur de podcast r\u00e9actif sur votre page Web Drupal. Utilisez notre d\u00e9mo accessible et cr\u00e9ez votre widget sur mesure en un clic !","og_url":"https:\/\/elfsight.com\/fr\/podcast-player-widget\/drupal\/","og_site_name":"Elfsight FR","article_modified_time":"2025-07-10T12:27:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elfsight.com\/fr\/podcast-player-widget\/drupal\/","url":"https:\/\/elfsight.com\/fr\/podcast-player-widget\/drupal\/","name":"Elfsight Podcast Player pour le site Drupal (facile et gratuit)","isPartOf":{"@id":"https:\/\/elfsight.com\/fr\/#website"},"datePublished":"1970-01-01T00:00:00+00:00","dateModified":"2025-07-10T12:27:37+00:00","description":"Utilisez notre d\u00e9mo pratique et ajoutez un lecteur de podcast r\u00e9actif sur votre page Web Drupal. Utilisez notre d\u00e9mo accessible et cr\u00e9ez votre widget sur mesure en un clic !","breadcrumb":{"@id":"https:\/\/elfsight.com\/fr\/podcast-player-widget\/drupal\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elfsight.com\/fr\/podcast-player-widget\/drupal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/elfsight.com\/fr\/podcast-player-widget\/drupal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elfsight.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Podcast Player","item":"https:\/\/elfsight.com\/fr\/podcast-player-widget\/"},{"@type":"ListItem","position":3,"name":"Podcast Player &#8211; Drupal"}]},{"@type":"WebSite","@id":"https:\/\/elfsight.com\/fr\/#website","url":"https:\/\/elfsight.com\/fr\/","name":"Elfsight FR","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elfsight.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"meta_box":{"industry":"","seo_heading":"","heading":"","description":"","cta_heading":"","cta_description":"","application":"2528","h1":"Module Lecteur de Podcasts Drupal","h1_caption":"Int\u00e9grez un lecteur de podcast directement sur votre site Web, permettant aux utilisateurs d'\u00e9couter vos \u00e9pisodes sans quitter la page de votre site Web Drupal, sans effort.","application_category":[],"applications_title":"","applications_request_title":"","applications_request_button_text":"","hero_text":"","hero_video":"","hero_video_schema_markup":"","selling_points_title":"","selling_points_caption":"","selling_points":[],"selling_points_cta_text":"","features_title":"","features":"","ed_cta_examples_text":"","ed_cta_examples_hidden":"","ed_cta_demo_text":"","ed_cta_demo_hidden":"","why_caption":"","why_editor_title":"","why_editor_text":"","why_team_title":"","why_team_text":"","why_service_title":"","why_service_text":"","template_catalog_visible":"","template_catalog_title":"","template_catalog_text":"","template_catalog_categories_visible":"","demo_title":"Cr\u00e9ez votre module Podcast Player","demo_caption":"Configurez votre Podcast Player et ajoutez-le gratuitement \u00e0 votre site Drupal\u00a0!","default_faq_hidden":"","app_template_category":[],"platform":"351","template_public_id":"","codecanyon_url":"","codecanyon_item_id":"","codecanyon_price":"","pricing_caption":"","pricing_elfsight_apps_hide_column":"","pricing_elfsight_apps_url":"","pricing_codecanyon_price_caption":"","integration_category":[],"integration_request_title":"","integration_request_cta":"","integration_platform":"","integrations":[],"platform_category":[],"video_schema_markup":"","price":"\u00e0 partir de 0$ \/ mois","trial":"","benefits":[{"text":"Assistance \u00e0 l'installation gratuite"},{"text":"Service client professionnel"},{"text":"Garantie de remboursement de 14 jours"},{"text":"Mises \u00e0 jour gratuites et continues"}],"button_url":"","button_target_blank":"","button_nofollow":"","attributes":[{"name":"Installations","content":"10,000 - 100,000"},{"name":"Sensible","content":"Oui"},{"name":"Navigateurs compatibles","content":"Firefox, Safari, Opera, Chrome, Edge"}],"tags":[],"tags_disable_links":"","hide_more_platforms":"","video_object":"","demo_hide_cta":"","demo_hide_cloud_options":"","pricing_title":"","pricing":[{"pricing_icon":"platform","pricing_title":"Elfsight Apps","pricing_title_caption":"Version ind\u00e9pendante de la plate-forme qui convient \u00e0 n'importe quel site Web","pricing_price":"from $0 \/ month","pricing_price_caption":"commencez avec un forfait gratuit","pricing_benefits":[{"text":"Sites Web illimit\u00e9s"},{"text":"Support client d\u00e9di\u00e9 et bien document\u00e9"},{"text":"Service d'installation gratuit"},{"text":"Prix \u200b\u200b\u00e0 attraper pour plusieurs applications"}],"pricing_button_text":"Ajouter au site Web","pricing_button_url":"#demo"}],"related_apps_title":"","related_apps_hidden":"","author":"","image":[],"title":"","job":"","social_networks":[]},"_links":{"self":[{"href":"https:\/\/elfsight.com\/fr\/wp-json\/wp\/v2\/pages\/9756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elfsight.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/elfsight.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/elfsight.com\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/elfsight.com\/fr\/wp-json\/wp\/v2\/comments?post=9756"}],"version-history":[{"count":2,"href":"https:\/\/elfsight.com\/fr\/wp-json\/wp\/v2\/pages\/9756\/revisions"}],"predecessor-version":[{"id":14910,"href":"https:\/\/elfsight.com\/fr\/wp-json\/wp\/v2\/pages\/9756\/revisions\/14910"}],"up":[{"embeddable":true,"href":"https:\/\/elfsight.com\/fr\/wp-json\/wp\/v2\/pages\/2529"}],"wp:attachment":[{"href":"https:\/\/elfsight.com\/fr\/wp-json\/wp\/v2\/media?parent=9756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}