{"id":10891,"date":"1970-01-01T00:00:00","date_gmt":"1970-01-01T00:00:00","guid":{"rendered":"https:\/\/elfsight.com\/fr\/?page_id=10891"},"modified":"2024-12-20T10:28:06","modified_gmt":"2024-12-20T10:28:06","slug":"html","status":"publish","type":"page","link":"https:\/\/elfsight.com\/fr\/viber-chat-widget\/html\/","title":{"rendered":"Viber Chat &#8211; HTML"},"content":{"rendered":"\n<div class=\"application-platform-content-item-description application-platform-content-item\" id=\"description\" data-nav-section=\"description\"> <h2>Description<\/h2><p>Elfsight Viber Chat est la possibilit\u00e9 la plus pratique pour les visiteurs du site Web de vous joindre en restant sur votre site Web. Chaque utilisateur obtiendra rapidement des r\u00e9ponses \u00e0 ses questions ou une assistance de votre part. Vous pourrez rester disponible en direct dans l&rsquo;une des messageries les plus utilis\u00e9es. Vous pouvez choisir Elfsight Viber Chat pour appara\u00eetre sur des pages particuli\u00e8res et le diriger vers certains groupes de visiteurs. Il existe une vari\u00e9t\u00e9 de possibilit\u00e9s de personnalisation\u00a0: choisissez les activateurs de d\u00e9marrage du chat, cr\u00e9ez votre texte de bienvenue, s\u00e9lectionnez les ic\u00f4nes et bien plus encore. En utilisant Viber Chat sur votre site, vous resterez joignable par les visiteurs \u00e0 tout moment et en tout lieu.<\/p><p><b>Ajoutez Viber Chat pour relever vos d\u00e9fis commerciaux avec moins d&rsquo;effort\u00a0!<\/b><\/p><\/div> <div class=\"application-platform-content-item-features application-platform-content-item\" id=\"features\" data-nav-section=\"features\"> <h2>Affichez la liste des fonctionnalit\u00e9s les plus importantes\u00a0:<\/h2><ul><li>Une collection d&rsquo;ic\u00f4nes de bulles \u00e0 choisir<\/li><li>Bulle modifiable text<\/li><li>En-t\u00eate de discussion avec logo, nom et l\u00e9gende de la page<\/li><li>Choisir l&rsquo;image de la page par d\u00e9faut, dans la collection ou t\u00e9l\u00e9charger votre propre image<\/li><li>Une option \u00e0 choisir texte personnalis\u00e9 comme l\u00e9gende<\/li><li>Le texte du bouton D\u00e9marrer le chat peut \u00eatre modifi\u00e9<\/li><\/ul><p><a href=\"#demo\">Examinez tous les param\u00e8tres dans la d\u00e9mo compl\u00e8te<\/a><\/p><\/div> <div class=\"application-platform-content-item-installation application-platform-content-item\" id=\"installation\" data-nav-section=\"installation\"> <h2>Comment puis-je ajouter Viber Chat \u00e0 mon site Web HTML\u00a0?<\/h2><p>Suivez simplement quelques \u00e9tapes ci-dessous pour activer l&rsquo;outil. .<\/p><ol><li><b>Ex\u00e9cutez notre \u00e9diteur gratuit et commencez \u00e0 fa\u00e7onner votre widget personnalis\u00e9.<\/b><br>D\u00e9terminez la conception et les fonctionnalit\u00e9s pr\u00e9f\u00e9r\u00e9es du widget et enregistrez les modifications.<\/li> <li><b>Copiez le code personnel qui s&rsquo;affiche dans la case sur les applications Elfsight<\/b><br>D\u00e8s que la personnalisation de votre widget personnel est termin\u00e9e, copiez le code individuel de la case qui appara\u00eet et conservez-le pour utilisation ult\u00e9rieure.<\/li><li><b>Entrez sur l&rsquo;utilisation du plugin sur la page d&rsquo;accueil HTML<\/b><br>Impl\u00e9mentez le code copi\u00e9 auparavant dans votre page d&rsquo;accueil et enregistrez les modifications.<\/li><li><b>Fait ! L&rsquo;int\u00e9gration est enti\u00e8rement termin\u00e9e.<\/b><br>Visitez votre page Web pour voir comment fonctionne l&rsquo;outil.<\/li><\/ol><p>Si vous rencontrez des difficult\u00e9s, n&rsquo;h\u00e9sitez pas \u00e0 \u00e9crire \u00e0 notre service client. . Nos collaborateurs sont impatients de vous aider \u00e0 r\u00e9soudre tous les probl\u00e8mes que vous pourriez rencontrer avec le widget.<\/p><div class=\"faq\" data-component=\"FAQ\"> <div class=\"faq-item\">\n\t\t\t\t\t<div class=\"faq-item-question\">\n\t\t\t\t\t\t<h3 class=\"faq-item-question-text\">Comment puis-je ajouter Viber Chat \u00e0 mon site Web HTML sans comp\u00e9tences en codage ?<\/h3>\n\n\t\t\t\t\t\t<div class=\"faq-item-question-icon\"><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"faq-item-answer\">\n\t\t\t\t\t\t<div class=\"faq-item-answer-text\"> <p>Elfsight fournit une solution SaaS qui vous permet de cr\u00e9er vous-m\u00eame un widget Viber Chat. Voyez \u00e0 quel point le processus est simple\u00a0: travaillez directement dans l&rsquo;\u00e9diteur en ligne pour cr\u00e9er un widget Viber Chat que vous aimeriez voir sur votre site Web HTML. Choisissez l&rsquo;un des mod\u00e8les pr\u00e9d\u00e9finis et ajustez les param\u00e8tres de Viber Chat, ajoutez votre contenu, modifiez la mise en page et les couleurs sans aucune comp\u00e9tence en codage. Enregistrez le Viber Chat et copiez son code d&rsquo;installation, afin que vous puissiez simplement l&rsquo;ajouter \u00e0 votre site Web HTML sans acheter de forfait payant. Gr\u00e2ce \u00e0 notre \u00e9diteur intuitif, tout internaute peut cr\u00e9er un widget Viber Chat en ligne et l&rsquo;int\u00e9grer facilement \u00e0 son site Web HTML. Il n&rsquo;est pas n\u00e9cessaire de payer ou de saisir les informations d&rsquo;identification de votre carte pour acc\u00e9der au service. Si vous rencontrez des probl\u00e8mes \u00e0 n&rsquo;importe quelle \u00e9tape, n&rsquo;h\u00e9sitez pas \u00e0 contacter notre \u00e9quipe d&rsquo;assistance technique.<\/p> <\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div> <\/div> <\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":0,"parent":2802,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-application-platform.php","meta":{"publish_to_discourse":"","publish_post_category":"","wpdc_auto_publish_overridden":"","wpdc_topic_tags":"","wpdc_pin_topic":"","wpdc_pin_until":"","discourse_post_id":"","discourse_permalink":"","wpdc_publishing_response":"","wpdc_publishing_error":"","footnotes":""},"class_list":["post-10891","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ajouter Viber Chat au site Web HTML sans codage (2026)<\/title>\n<meta name=\"description\" content=\"Int\u00e9grez Viber Chat sur le site Web pour une connexion fluide et plus rapide avec les visiteurs. Essayez la d\u00e9mo gratuite d&#039;Elfsight pour cr\u00e9er votre propre plugin d\u00e8s maintenant.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elfsight.com\/fr\/viber-chat-widget\/html\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ajouter Viber Chat au site Web HTML sans codage (2026)\" \/>\n<meta property=\"og:description\" content=\"Int\u00e9grez Viber Chat sur le site Web pour une connexion fluide et plus rapide avec les visiteurs. Essayez la d\u00e9mo gratuite d&#039;Elfsight pour cr\u00e9er votre propre plugin d\u00e8s maintenant.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elfsight.com\/fr\/viber-chat-widget\/html\/\" \/>\n<meta property=\"og:site_name\" content=\"Elfsight FR\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-20T10:28:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ajouter Viber Chat au site Web HTML sans codage (2026)","description":"Int\u00e9grez Viber Chat sur le site Web pour une connexion fluide et plus rapide avec les visiteurs. Essayez la d\u00e9mo gratuite d'Elfsight pour cr\u00e9er votre propre plugin d\u00e8s maintenant.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elfsight.com\/fr\/viber-chat-widget\/html\/","og_locale":"fr_FR","og_type":"article","og_title":"Ajouter Viber Chat au site Web HTML sans codage (2026)","og_description":"Int\u00e9grez Viber Chat sur le site Web pour une connexion fluide et plus rapide avec les visiteurs. Essayez la d\u00e9mo gratuite d'Elfsight pour cr\u00e9er votre propre plugin d\u00e8s maintenant.","og_url":"https:\/\/elfsight.com\/fr\/viber-chat-widget\/html\/","og_site_name":"Elfsight FR","article_modified_time":"2024-12-20T10:28:06+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elfsight.com\/fr\/viber-chat-widget\/html\/","url":"https:\/\/elfsight.com\/fr\/viber-chat-widget\/html\/","name":"Ajouter Viber Chat au site Web HTML sans codage (2026)","isPartOf":{"@id":"https:\/\/elfsight.com\/fr\/#website"},"datePublished":"1970-01-01T00:00:00+00:00","dateModified":"2024-12-20T10:28:06+00:00","description":"Int\u00e9grez Viber Chat sur le site Web pour une connexion fluide et plus rapide avec les visiteurs. Essayez la d\u00e9mo gratuite d'Elfsight pour cr\u00e9er votre propre plugin d\u00e8s maintenant.","breadcrumb":{"@id":"https:\/\/elfsight.com\/fr\/viber-chat-widget\/html\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elfsight.com\/fr\/viber-chat-widget\/html\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/elfsight.com\/fr\/viber-chat-widget\/html\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elfsight.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Viber Chat","item":"https:\/\/elfsight.com\/fr\/viber-chat-widget\/"},{"@type":"ListItem","position":3,"name":"Viber Chat &#8211; HTML"}]},{"@type":"WebSite","@id":"https:\/\/elfsight.com\/fr\/#website","url":"https:\/\/elfsight.com\/fr\/","name":"Elfsight FR","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elfsight.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"meta_box":{"industry":"","seo_heading":"","heading":"","description":"","cta_heading":"","cta_description":"","application":"2799","h1":"Chat Viber HTML","h1_caption":"Proposez Viber comme canal de communication sur votre site Web, permettant aux visiteurs d'acc\u00e9der facilement \u00e0 votre site Web HTML sans effort.","application_category":[],"applications_title":"","applications_request_title":"","applications_request_button_text":"","hero_text":"","hero_video":"","hero_video_schema_markup":"","selling_points_title":"","selling_points_caption":"","selling_points":[],"selling_points_cta_text":"","features_title":"","features":"","ed_cta_examples_text":"","ed_cta_examples_hidden":"","ed_cta_demo_text":"","ed_cta_demo_hidden":"","why_caption":"","why_editor_title":"","why_editor_text":"","why_team_title":"","why_team_text":"","why_service_title":"","why_service_text":"","template_catalog_visible":"0","template_catalog_title":"","template_catalog_text":"","template_catalog_categories_visible":"","demo_title":"Cr\u00e9ez votre widget Viber Chat","demo_caption":"Configurez votre Viber Chat et ajoutez-le \u00e0 votre site Web HTML gratuitement\u00a0!","default_faq_hidden":"","app_template_category":[],"platform":"352","template_public_id":"","codecanyon_url":"","codecanyon_item_id":"","codecanyon_price":"","pricing_caption":"","pricing_elfsight_apps_hide_column":"","pricing_elfsight_apps_url":"","pricing_codecanyon_price_caption":"","integration_category":[],"integration_request_title":"","integration_request_cta":"","integration_platform":"","integrations":[],"platform_category":[],"video_schema_markup":"","price":"\u00e0 partir de 0$ \/ mois","trial":"","benefits":[{"text":"Aide \u00e0 l'installation gratuite"},{"text":"Assistance premium"},{"text":"Garantie de remboursement de 14 jours"},{"text":"Mises \u00e0 jour gratuites en continu"}],"button_url":"","button_target_blank":"0","button_nofollow":"0","attributes":[{"name":"Installations","content":"10,000 - 100,000"},{"name":"Sensible","content":"Oui"},{"name":"Navigateurs compatibles","content":"Firefox, Safari, Opera, Chrome, Edge"}],"tags":[],"tags_disable_links":"0","hide_more_platforms":"","video_object":"","demo_hide_cta":"0","demo_hide_cloud_options":"0","pricing_title":"","pricing":[{"pricing_icon":"platform","pricing_title":"Elfsight Apps","pricing_title_caption":"Logiciel multiplateforme","pricing_price":"from $0 \/ month","pricing_price_caption":"commencez avec un forfait gratuit","pricing_benefits":[{"text":"Sites Web illimit\u00e9s"},{"text":"Assistance premium et ponctuelle"},{"text":"Assistance \u00e0 l'installation gratuite"},{"text":"Offre sp\u00e9ciale pour plusieurs applications"}],"pricing_button_text":"Ajouter au site Web","pricing_button_url":"#demo"}],"related_apps_title":"","related_apps_hidden":"0","author":"","image":[],"title":"","job":"","social_networks":[]},"_links":{"self":[{"href":"https:\/\/elfsight.com\/fr\/wp-json\/wp\/v2\/pages\/10891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elfsight.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/elfsight.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/elfsight.com\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/elfsight.com\/fr\/wp-json\/wp\/v2\/comments?post=10891"}],"version-history":[{"count":2,"href":"https:\/\/elfsight.com\/fr\/wp-json\/wp\/v2\/pages\/10891\/revisions"}],"predecessor-version":[{"id":15959,"href":"https:\/\/elfsight.com\/fr\/wp-json\/wp\/v2\/pages\/10891\/revisions\/15959"}],"up":[{"embeddable":true,"href":"https:\/\/elfsight.com\/fr\/wp-json\/wp\/v2\/pages\/2802"}],"wp:attachment":[{"href":"https:\/\/elfsight.com\/fr\/wp-json\/wp\/v2\/media?parent=10891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}