{"id":4369,"date":"2022-02-11T11:24:01","date_gmt":"2022-02-11T11:24:01","guid":{"rendered":"https:\/\/elfsight.com\/es\/?page_id=4369"},"modified":"2025-02-06T15:22:30","modified_gmt":"2025-02-06T15:22:30","slug":"iframe","status":"publish","type":"page","link":"https:\/\/elfsight.com\/es\/online-form-builder\/iframe\/","title":{"rendered":"Form Builder &#8211; iFrame"},"content":{"rendered":"<div class=\"application-platform-content-item-description application-platform-content-item\" id=\"description\" data-nav-section=\"description\"><h2>Constructor de formularios personalizado para iFrame<\/h2><p>Elfsight Builder es un plugin para crear infinitos tipos de formularios y mostrarlos en cualquier recurso web. Recoge datos de tus clientes actuales y potenciales mediante encuestas, formularios de retroalimentaci\u00f3n, solicitudes de valoraci\u00f3n y otras variantes f\u00e1ciles de completar. Define la estructura del formulario, selecciona construir formularios \u00fanicos para obtener m\u00e1s informaci\u00f3n de tus clientes. No importa qu\u00e9 tipo de informaci\u00f3n planeas recoger: ideas, valoraciones, reservas o compras, el Form Builder de Elfsight te ayudar\u00e1 a crear el formulario adecuado para ello. Con una estructura flexible y una amplia gama de segmentos predefinidos, tu formulario ser\u00e1 manejable para tus clientes y efectivo para ti.<\/p> <p><b>\u00a1Recibe opiniones, ideas y valoraciones de los clientes para mejorar tu negocio!<\/b><\/p> <p><b>Crea formularios atractivos para recoger m\u00e1s retroalimentaci\u00f3n<\/b><br> Utiliza todos los par\u00e1metros del plugin Elfsight para crear formularios de alta eficiencia. Selecciona los elementos necesarios y define la estructura para que tus formularios sean ordenados y f\u00e1ciles de completar. Utiliza opciones de estilo para darles un aspecto atractivo y obtener m\u00e1s retroalimentaci\u00f3n.<\/p><p><b>Aumenta la cantidad de leads con formularios f\u00e1ciles de gestionar<\/b><br> No dejes que los clientes abandonen el formulario incompleto y sin datos valiosos. Dise\u00f1a formularios con pasos simples y una estructura f\u00e1cil que mantendr\u00e1 a los clientes comprometidos hasta el final y aumentar\u00e1 la cantidad de leads.<\/p><p><b>Ahorra tiempo y dinero con una herramienta multifuncional<\/b><br> Esta herramienta \u00fanica permite crear formularios con diversos ejemplos, conjuntos de componentes y estructuras. Esto te ayudar\u00e1 a generar formularios para obtener retroalimentaci\u00f3n de diversas categor\u00edas sin gastar m\u00e1s dinero ni tiempo.<\/p><\/div><div class=\"application-platform-content-item-features application-platform-content-item\" id=\"features\" data-nav-section=\"features\"><h2>Caracter\u00edsticas del plugin Form Builder<\/h2><p>\u00bfQu\u00e9 hace que Elfsight Form Builder sea el mejor plugin para recoger todo tipo de informaci\u00f3n de los clientes en sitios web iFrame? Consulta la lista de opciones que incluye:<\/p><ul><li>Muestra el encabezado del formulario con t\u00edtulo y texto;<\/li><li>Utiliza marcadores de posici\u00f3n en los campos para dar ejemplos de relleno correcto y el tipo de datos necesario;<\/li><li>Asigna cualquier direcci\u00f3n de correo electr\u00f3nico y los resultados del formulario se enviar\u00e1n autom\u00e1ticamente all\u00ed;<\/li><li>3 dise\u00f1os listos para usar (Predeterminado, Caja, Flotante);<\/li><li>5 estilos predefinidos para los campos del formulario;<\/li><li>Genera formularios ilimitados para recoger datos de los clientes.<\/li><\/ul><p><a href=\"#demo\">Consulta las caracter\u00edsticas en la demo de Elfsight<\/a><\/p><\/div><div class=\"application-platform-content-item-installation application-platform-content-item\" id=\"installation\" data-nav-section=\"installation\"><h2>\u00bfC\u00f3mo agregar el plugin Form Builder a un sitio web iFrame?<\/h2><p>Un peque\u00f1o tutorial para integrar y configurar el plugin sin experiencia en desarrollo web. El proceso tomar\u00e1 aproximadamente 2 minutos.<\/p><ol><li><b>Crea tu propio plugin de formulario<\/b><br> En nuestro editor gratuito, crea un plugin con una interfaz y funciones personalizadas.<\/li><li><b>Copia el c\u00f3digo personal para agregar el plugin<\/b><br> Despu\u00e9s de crear tu plugin, obtendr\u00e1s un c\u00f3digo personal en la ventana emergente de Elfsight Apps. Copia el c\u00f3digo para usarlo m\u00e1s tarde.<\/li> <li><b>El plugin en tu sitio iFrame<\/b><br> Define el lugar donde deseas mostrar el plugin y pega el c\u00f3digo copiado all\u00ed. Guarda los resultados.<\/li> <li><b>\u00a1Felicidades! Has integrado el plugin con \u00e9xito!<\/b><br> Ve a tu p\u00e1gina para verificar tu formulario.<\/li> <\/ol><p>\u00bfTuviste dificultades o preguntas al realizar el tutorial o al crear tu plugin? Consulta nuestro tutorial completo \u00ab\u00bfC\u00f3mo insertar formularios en un sitio iFrame?\u00bb o contacta con el soporte al cliente.<\/p><div class=\"faq\" data-component=\"FAQ\"> <div class=\"faq-item\">\n\t\t\t\t\t<div class=\"faq-item-question\">\n\t\t\t\t\t\t<h3 class=\"faq-item-question-text\">\u00bfC\u00f3mo agregar Form Builder a mi sitio iFrame sin conocimientos de programaci\u00f3n?<\/h3>\n\n\t\t\t\t\t\t<div class=\"faq-item-question-icon\"><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"faq-item-answer\">\n\t\t\t\t\t\t<div class=\"faq-item-answer-text\"> <p>Elfsight ofrece una soluci\u00f3n SaaS que te permite crear un widget Form Builder t\u00fa mismo, y ver lo f\u00e1cil que es el proceso: Trabaja directamente en el Editor en l\u00ednea para crear el widget Form Builder que deseas ver en tu sitio iFrame. Elige una de las plantillas predise\u00f1adas y ajusta la configuraci\u00f3n de Form Builder, agrega tu contenido, cambia el dise\u00f1o y los colores sin necesidad de habilidades de programaci\u00f3n. Guarda el Form Builder y copia su c\u00f3digo de instalaci\u00f3n, que puedes agregar f\u00e1cilmente a tu sitio iFrame sin necesidad de comprar un plan de pago. Con nuestro Editor intuitivo, cualquier usuario de Internet puede crear el widget Form Builder en l\u00ednea e incrustarlo f\u00e1cilmente en su sitio iFrame. No es necesario pagar ni ingresar tus datos bancarios para acceder al servicio. Si tienes alg\u00fan problema en cualquier paso, no dudes en contactar con nuestro equipo de soporte t\u00e9cnico.<\/p> <\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><div class=\"faq-item\">\n\t\t\t\t\t<div class=\"faq-item-question\">\n\t\t\t\t\t\t<h3 class=\"faq-item-question-text\">\u00bfExisten plantillas personalizadas para Form Builder en sitios iFrame?<\/h3>\n\n\t\t\t\t\t\t<div class=\"faq-item-question-icon\"><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"faq-item-answer\">\n\t\t\t\t\t\t<div class=\"faq-item-answer-text\"><p>S\u00ed. Elfsight ha preparado una gran selecci\u00f3n de m\u00e1s de 300 <a href=\"https:\/\/elfsight.com\/online-form-builder\/templates\/\">plantillas de Form Builder<\/a> con elementos y caracter\u00edsticas personalizables. Puedes encontrar una plantilla de formulario para cualquier ocasi\u00f3n, como <a href=\"https:\/\/elfsight.com\/online-form-builder\/templates\/application-forms\/\">formularios de solicitud<\/a>, <a href=\"https:\/\/elfsight.com\/online-form-builder\/templates\/booking-forms\/\">formularios de reserva<\/a>, <a href=\"https:\/\/elfsight.com\/online-form-builder\/templates\/order-forms\/\">formularios de pedido<\/a>, <a href=\"https:\/\/elfsight.com\/online-form-builder\/templates\/product-forms\/\">formularios de producto<\/a>, <a href=\"https:\/\/elfsight.com\/online-form-builder\/templates\/questionnaires\/\">cuestionarios<\/a>, <a href=\"https:\/\/elfsight.com\/online-form-builder\/templates\/quizzes\/\">quizzes<\/a>, <a href=\"https:\/\/elfsight.com\/online-form-builder\/templates\/surveys\/\">encuestas<\/a>, <a href=\"https:\/\/elfsight.com\/online-form-builder\/templates\/file-upload-forms\/\">formularios de carga de archivos<\/a>, y muchos m\u00e1s.<\/p><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div> <\/div> <\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":18,"featured_media":0,"parent":1746,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-application-platform.php","meta":{"publish_to_discourse":"","publish_post_category":"","wpdc_auto_publish_overridden":"","wpdc_topic_tags":"","wpdc_pin_topic":"","wpdc_pin_until":"","discourse_post_id":"","discourse_permalink":"","wpdc_publishing_response":"","wpdc_publishing_error":"","footnotes":""},"class_list":["post-4369","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Constructor de formularios - Empotrar widget de Generador de formularios al iFrame<\/title>\n<meta name=\"description\" content=\"Instala un widget interactivo de Constructor de formularios en su sitio web de iFrame. Aplique la demo de Elfsight f\u00e1cil de usar y construe su widget personalizado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elfsight.com\/es\/online-form-builder\/iframe\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Constructor de formularios - Empotrar widget de Generador de formularios al iFrame\" \/>\n<meta property=\"og:description\" content=\"Instala un widget interactivo de Constructor de formularios en su sitio web de iFrame. Aplique la demo de Elfsight f\u00e1cil de usar y construe su widget personalizado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elfsight.com\/es\/online-form-builder\/iframe\/\" \/>\n<meta property=\"og:site_name\" content=\"Elfsight ES\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-06T15:22:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Constructor de formularios - Empotrar widget de Generador de formularios al iFrame","description":"Instala un widget interactivo de Constructor de formularios en su sitio web de iFrame. Aplique la demo de Elfsight f\u00e1cil de usar y construe su widget personalizado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elfsight.com\/es\/online-form-builder\/iframe\/","og_locale":"es_ES","og_type":"article","og_title":"Constructor de formularios - Empotrar widget de Generador de formularios al iFrame","og_description":"Instala un widget interactivo de Constructor de formularios en su sitio web de iFrame. Aplique la demo de Elfsight f\u00e1cil de usar y construe su widget personalizado.","og_url":"https:\/\/elfsight.com\/es\/online-form-builder\/iframe\/","og_site_name":"Elfsight ES","article_modified_time":"2025-02-06T15:22:30+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elfsight.com\/es\/online-form-builder\/iframe\/","url":"https:\/\/elfsight.com\/es\/online-form-builder\/iframe\/","name":"Constructor de formularios - Empotrar widget de Generador de formularios al iFrame","isPartOf":{"@id":"https:\/\/elfsight.com\/es\/#website"},"datePublished":"2022-02-11T11:24:01+00:00","dateModified":"2025-02-06T15:22:30+00:00","description":"Instala un widget interactivo de Constructor de formularios en su sitio web de iFrame. Aplique la demo de Elfsight f\u00e1cil de usar y construe su widget personalizado.","breadcrumb":{"@id":"https:\/\/elfsight.com\/es\/online-form-builder\/iframe\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elfsight.com\/es\/online-form-builder\/iframe\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/elfsight.com\/es\/online-form-builder\/iframe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elfsight.com\/es\/"},{"@type":"ListItem","position":2,"name":"Form Builder","item":"https:\/\/elfsight.com\/es\/online-form-builder\/"},{"@type":"ListItem","position":3,"name":"Form Builder &#8211; iFrame"}]},{"@type":"WebSite","@id":"https:\/\/elfsight.com\/es\/#website","url":"https:\/\/elfsight.com\/es\/","name":"Elfsight ES","description":"Just another Elfsight Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elfsight.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"meta_box":{"industry":"","seo_heading":"","heading":"","description":"","cta_heading":"","cta_description":"","application":"1745","h1":"widget de Constructor de formularios para iFrame","h1_caption":"Construye formas convencionales y multinivel y ins\u00e9rtelos a su sitio","application_category":[],"applications_title":"","applications_request_title":"","applications_request_button_text":"","hero_text":"","hero_video":"","hero_video_schema_markup":"","selling_points_title":"","selling_points_caption":"","selling_points":[],"selling_points_cta_text":"","features_title":"","features":"","ed_cta_examples_text":"","ed_cta_examples_hidden":"","ed_cta_demo_text":"","ed_cta_demo_hidden":"","why_caption":"","why_editor_title":"","why_editor_text":"","why_team_title":"","why_team_text":"","why_service_title":"","why_service_text":"","template_catalog_visible":"","template_catalog_title":"","template_catalog_text":"","template_catalog_categories_visible":"","demo_title":"Crea tu widget de Creador de formularios","demo_caption":"\u00a1Configure su Creador de formularios y agr\u00e9guelo a su sitio web iFrame gratis!","default_faq_hidden":"","app_template_category":[],"platform":"2192","template_public_id":"","codecanyon_url":"","codecanyon_item_id":"","codecanyon_price":"","pricing_caption":"","pricing_elfsight_apps_hide_column":"","pricing_elfsight_apps_url":"","pricing_codecanyon_price_caption":"","integration_category":[],"integration_request_title":"","integration_request_cta":"","integration_platform":"","integrations":[],"platform_category":[],"video_schema_markup":"","price":"desde $0 por mes","trial":"","benefits":[{"text":"Instalaci\u00f3n gratuita"},{"text":"Soporte Premium"},{"text":"14 d\u00edas garant\u00eda de reembolso"},{"text":"Actualizaciones regulares"}],"button_url":"#demo","button_target_blank":"0","button_nofollow":"0","attributes":[{"name":"Responsivo","content":"Si","_state":"expanded"},{"name":"Navegadores compatibles","content":"Firefox, Safari, Opera, Chrome, Edge","_state":"expanded"}],"tags":[],"tags_disable_links":"0","hide_more_platforms":"","video_object":"","demo_hide_cta":"0","demo_hide_cloud_options":"0","pricing_title":"","pricing":[{"pricing_icon":"platform","pricing_title":" Elfsight Apps","pricing_title_caption":"Soluci\u00f3n multiplataforma - valido para cualquier p\u00e1gina web","pricing_price":"desde $0 por mes","pricing_price_caption":"empezar con un plan gratuito","pricing_benefits":[{"text":"Sitios web ilimitados"},{"text":"Atenci\u00f3n al cliente gratuita y r\u00e1pida"},{"text":"Servicio de instalaci\u00f3n gratuito"},{"text":"Totalmente personalizable"}],"pricing_button_text":"Agregar al sitio web","pricing_button_url":"#demo","_state":"expanded"}],"related_apps_title":"","related_apps_hidden":"1","author":"","image":[],"title":"","job":"","social_networks":[]},"_links":{"self":[{"href":"https:\/\/elfsight.com\/es\/wp-json\/wp\/v2\/pages\/4369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elfsight.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/elfsight.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/elfsight.com\/es\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/elfsight.com\/es\/wp-json\/wp\/v2\/comments?post=4369"}],"version-history":[{"count":3,"href":"https:\/\/elfsight.com\/es\/wp-json\/wp\/v2\/pages\/4369\/revisions"}],"predecessor-version":[{"id":18187,"href":"https:\/\/elfsight.com\/es\/wp-json\/wp\/v2\/pages\/4369\/revisions\/18187"}],"up":[{"embeddable":true,"href":"https:\/\/elfsight.com\/es\/wp-json\/wp\/v2\/pages\/1746"}],"wp:attachment":[{"href":"https:\/\/elfsight.com\/es\/wp-json\/wp\/v2\/media?parent=4369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}