{"id":19637,"date":"2025-05-19T15:09:24","date_gmt":"2025-05-19T15:09:24","guid":{"rendered":"https:\/\/elfsight.com\/es\/?page_id=19637"},"modified":"2025-05-28T14:56:56","modified_gmt":"2025-05-28T14:56:56","slug":"features","status":"publish","type":"page","link":"https:\/\/elfsight.com\/es\/accessibility-widget\/features\/","title":{"rendered":"Accessibility &#8211; Features"},"content":{"rendered":"<section class=\"application-features-group section\" id=\"ACCESSIBILITY MODES\">\n                    <div class=\"inner\">\n                        <div class=\"col-row\">\n                            <div class=\"col-6 col-offset-3 col-m-12 col-m-offset-0\"><h3>Modos listos para cada usuario<\/h3><p>Elija entre 8 modos predefinidos adaptados a necesidades reales de accesibilidad, como Baja Visi\u00f3n, Amigable con Dislexia o Seguro para Crisis Epil\u00e9pticas, cada uno agrupando m\u00faltiples configuraciones \u00fatiles en un solo clic.<\/p><h3>Ajustes inteligentes de visual y texto<\/h3><p>Mejore la legibilidad con 8 configuraciones dedicadas como redimensionar texto, espaciado de l\u00edneas y fuentes de alto contraste, todas dise\u00f1adas para facilitar la lectura de su contenido.<\/p><h3>Mejor navegaci\u00f3n para todos los usuarios<\/h3><p>Active 4 funciones clave que simplifican el movimiento por su sitio, desde navegaci\u00f3n compatible con teclado hasta \u00e1reas clicables m\u00e1s grandes para un mejor control.<\/p><h3>Retroalimentaci\u00f3n visual y opciones de control<\/h3><p>Filtros de color (7 tipos), indicador de modo activo, bot\u00f3n de reinicio y ajustes de duraci\u00f3n brindan a los usuarios control total sobre su experiencia y les informan cu\u00e1ndo el soporte est\u00e1 activo.<\/p><\/div>\n                        <\/div>\n                    <\/div>\n\n                    <div class=\"application-features-group-title\">MODOS DE ACCESIBILIDAD<\/div>\n                <\/section><section class=\"application-features-group section\" style=\"background-color:#fafafa;\" id=\"BUILT-IN AUDIT\">\n                    <div class=\"inner\">\n                        <div class=\"col-row\">\n                            <div class=\"col-6 col-offset-3 col-m-12 col-m-offset-0\"><h3>Realice chequeos de accesibilidad en segundos<\/h3><p>Use el verificador integrado para escanear su sitio web, recibir una puntuaci\u00f3n de accesibilidad y explorar consejos detallados para mejorar, sin necesidad de herramientas externas.<\/p><h3>Acceda al historial completo de auditor\u00edas<\/h3><p>Controle su progreso con informes descargables que registran auditor\u00edas pasadas y resaltan problemas resueltos.<\/p><h3>Fomente la confianza del usuario con una insignia<\/h3><p>Muestre su puntuaci\u00f3n de accesibilidad actual dentro del widget como un elemento visual de confianza para tranquilizar a los visitantes y mostrar transparencia.<\/p><h3>Comparta su progreso en accesibilidad<\/h3><p>Personalice un mensaje corto en el widget para informar a los usuarios que est\u00e1 trabajando activamente para un sitio web m\u00e1s accesible.<\/p><\/div>\n                        <\/div>\n                    <\/div>\n\n                    <div class=\"application-features-group-title\">AUDITOR\u00cdA INTEGRADA<\/div>\n                <\/section><section class=\"application-features-group section\" id=\"BADGE DISPLAY\">\n                    <div class=\"inner\">\n                        <div class=\"col-row\">\n                            <div class=\"col-6 col-offset-3 col-m-12 col-m-offset-0\"><h3>Haga visible la accesibilidad<\/h3><p>Agregue una insignia de confianza a su sitio que muestre su puntuaci\u00f3n de accesibilidad en tiempo real, demostrando a los visitantes que su sitio cumple con los est\u00e1ndares inclusivos.<\/p><h3>Perfecto para m\u00f3vil y escritorio<\/h3><p>El widget soporta una vista dividida responsiva para m\u00f3viles, y puede configurar f\u00e1cilmente su visibilidad por p\u00e1gina o tipo de dispositivo.<\/p><\/div>\n                        <\/div>\n                    <\/div>\n\n                    <div class=\"application-features-group-title\">MOSTRAR INSIGNIA<\/div>\n                <\/section><section class=\"application-features-group section\" style=\"background-color:#fafafa;\" id=\"LOCALIZATION\">\n                    <div class=\"inner\">\n                        <div class=\"col-row\">\n                            <div class=\"col-6 col-offset-3 col-m-12 col-m-offset-0\"><h3>Localizaci\u00f3n para alcance global<\/h3><p>El widget est\u00e1 traducido a 76 idiomas y localizado para formatos regionales, asegurando claridad para visitantes de todo el mundo.<\/p><h3>Colocaci\u00f3n flexible del widget<\/h3><p>Posicione el widget exactamente donde quiera \u2014 abajo a la izquierda, derecha, flotante o fijo \u2014 para que encaje naturalmente en el dise\u00f1o de su sitio web.<\/p><\/div>\n                        <\/div>\n                    <\/div>\n\n                    <div class=\"application-features-group-title\">LOCALIZACI\u00d3N<\/div>\n                <\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":0,"parent":19635,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-application-features.php","meta":{"publish_to_discourse":"","publish_post_category":"","wpdc_auto_publish_overridden":"","wpdc_topic_tags":"","wpdc_pin_topic":"","wpdc_pin_until":"","discourse_post_id":"","discourse_permalink":"","wpdc_publishing_response":"","wpdc_publishing_error":"","footnotes":""},"class_list":["post-19637","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Funciones del widget de accesibilidad para su sitio web (configuraciones personalizadas)<\/title>\n<meta name=\"description\" content=\"Pruebe todas las funciones del widget de accesibilidad en el editor en vivo. Configuraciones personalizadas y un dise\u00f1o de widget totalmente responsivo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elfsight.com\/es\/accessibility-widget\/features\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Funciones del widget de accesibilidad para su sitio web (configuraciones personalizadas)\" \/>\n<meta property=\"og:description\" content=\"Pruebe todas las funciones del widget de accesibilidad en el editor en vivo. Configuraciones personalizadas y un dise\u00f1o de widget totalmente responsivo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elfsight.com\/es\/accessibility-widget\/features\/\" \/>\n<meta property=\"og:site_name\" content=\"Elfsight ES\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-28T14:56:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Funciones del widget de accesibilidad para su sitio web (configuraciones personalizadas)","description":"Pruebe todas las funciones del widget de accesibilidad en el editor en vivo. Configuraciones personalizadas y un dise\u00f1o de widget totalmente responsivo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elfsight.com\/es\/accessibility-widget\/features\/","og_locale":"es_ES","og_type":"article","og_title":"Funciones del widget de accesibilidad para su sitio web (configuraciones personalizadas)","og_description":"Pruebe todas las funciones del widget de accesibilidad en el editor en vivo. Configuraciones personalizadas y un dise\u00f1o de widget totalmente responsivo.","og_url":"https:\/\/elfsight.com\/es\/accessibility-widget\/features\/","og_site_name":"Elfsight ES","article_modified_time":"2025-05-28T14:56:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elfsight.com\/es\/accessibility-widget\/features\/","url":"https:\/\/elfsight.com\/es\/accessibility-widget\/features\/","name":"Funciones del widget de accesibilidad para su sitio web (configuraciones personalizadas)","isPartOf":{"@id":"https:\/\/elfsight.com\/es\/#website"},"datePublished":"2025-05-19T15:09:24+00:00","dateModified":"2025-05-28T14:56:56+00:00","description":"Pruebe todas las funciones del widget de accesibilidad en el editor en vivo. Configuraciones personalizadas y un dise\u00f1o de widget totalmente responsivo.","breadcrumb":{"@id":"https:\/\/elfsight.com\/es\/accessibility-widget\/features\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elfsight.com\/es\/accessibility-widget\/features\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/elfsight.com\/es\/accessibility-widget\/features\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elfsight.com\/es\/"},{"@type":"ListItem","position":2,"name":"Accessibility &#8211; Features"}]},{"@type":"WebSite","@id":"https:\/\/elfsight.com\/es\/#website","url":"https:\/\/elfsight.com\/es\/","name":"Elfsight ES","description":"Just another Elfsight Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elfsight.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"meta_box":{"industry":"","seo_heading":"","heading":"","description":"","cta_heading":"","cta_description":"","application":"19630","h1":"","h1_caption":"","application_category":[],"applications_title":"","applications_request_title":"","applications_request_button_text":"","hero_text":"","hero_video":"","hero_video_schema_markup":"","selling_points_title":"","selling_points_caption":"","selling_points":[],"selling_points_cta_text":"","features_title":"","features":"","ed_cta_examples_text":"","ed_cta_examples_hidden":"","ed_cta_demo_text":"","ed_cta_demo_hidden":"","why_caption":"","why_editor_title":"","why_editor_text":"","why_team_title":"","why_team_text":"","why_service_title":"","why_service_text":"","template_catalog_visible":"","template_catalog_title":"","template_catalog_text":"","template_catalog_categories_visible":"","demo_title":"","demo_caption":"","default_faq_hidden":"","app_template_category":[],"platform":"","template_public_id":"","codecanyon_url":"","codecanyon_item_id":"","codecanyon_price":"","pricing_caption":"","pricing_elfsight_apps_hide_column":"","pricing_elfsight_apps_url":"","pricing_codecanyon_price_caption":"","integration_category":[],"integration_request_title":"","integration_request_cta":"","integration_platform":"","integrations":[],"platform_category":[],"video_schema_markup":"","price":"","trial":"","benefits":[],"button_url":"","button_target_blank":"","button_nofollow":"","attributes":[],"tags":[],"tags_disable_links":"","hide_more_platforms":"","video_object":"","demo_hide_cta":"","demo_hide_cloud_options":"","pricing_title":"","pricing":[],"related_apps_title":"","related_apps_hidden":"","author":"","image":[],"title":"","job":"","social_networks":[]},"_links":{"self":[{"href":"https:\/\/elfsight.com\/es\/wp-json\/wp\/v2\/pages\/19637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elfsight.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/elfsight.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/elfsight.com\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/elfsight.com\/es\/wp-json\/wp\/v2\/comments?post=19637"}],"version-history":[{"count":1,"href":"https:\/\/elfsight.com\/es\/wp-json\/wp\/v2\/pages\/19637\/revisions"}],"predecessor-version":[{"id":19638,"href":"https:\/\/elfsight.com\/es\/wp-json\/wp\/v2\/pages\/19637\/revisions\/19638"}],"up":[{"embeddable":true,"href":"https:\/\/elfsight.com\/es\/wp-json\/wp\/v2\/pages\/19635"}],"wp:attachment":[{"href":"https:\/\/elfsight.com\/es\/wp-json\/wp\/v2\/media?parent=19637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}