{"id":2871,"date":"2020-09-15T08:29:01","date_gmt":"2020-09-15T08:29:01","guid":{"rendered":"https:\/\/elfsight.com\/de\/?page_id=2871"},"modified":"2022-03-21T09:18:37","modified_gmt":"2022-03-21T09:18:37","slug":"pricing","status":"publish","type":"page","link":"https:\/\/elfsight.com\/de\/click-to-call-widget\/pricing\/","title":{"rendered":"Click to Call &#8211; Pricing"},"content":{"rendered":"\n<div class=\"faq\" data-component=\"FAQ\">\n<div class=\"faq-item\">\n\t\t\t\t\t<div class=\"faq-item-question\">\n\t\t\t\t\t\t<h3 class=\"faq-item-question-text\">Kann ich Elfsight-Plugins kostenlos herunterladen?<\/h3>\n\n\t\t\t\t\t\t<div class=\"faq-item-question-icon\"><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"faq-item-answer\">\n\t\t\t\t\t\t<div class=\"faq-item-answer-text\">\n\nJa, stimmt. Unsere Firma bringt ein kostenloses Abonnement f\u00fcr die Widgets. Dar\u00fcber hinaus beschr\u00e4nken wir die wesentlichen Funktionalit\u00e4t und die Bearbeitungsoptionen nicht. Beeilen Sie sich alle Pluspunkte gratis Elfsight-Widgets f\u00fcr Ihre Website zu nutzen. \n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n<div class=\"faq-item\">\n\t\t\t\t\t<div class=\"faq-item-question\">\n\t\t\t\t\t\t<h3 class=\"faq-item-question-text\">Haben Sie eine Probezeit f\u00fcr Ihre Apps?<\/h3>\n\n\t\t\t\t\t\t<div class=\"faq-item-question-icon\"><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"faq-item-answer\">\n\t\t\t\t\t\t<div class=\"faq-item-answer-text\">\n\nElfsight Gratisabonnement hat keine Testzeitraum. Sie k\u00f6nnen das Widget auf der Site so lange verwenden, wie Sie es brauchen. \n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n<div class=\"faq-item\">\n\t\t\t\t\t<div class=\"faq-item-question\">\n\t\t\t\t\t\t<h3 class=\"faq-item-question-text\">Bietet Elfsight einige Rabatte?<\/h3>\n\n\t\t\t\t\t\t<div class=\"faq-item-question-icon\"><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"faq-item-answer\">\n\t\t\t\t\t\t<div class=\"faq-item-answer-text\">\n\nSicher, Sie k\u00f6nnen 20% Willkommensrabatt f\u00fcr Ihr erstes Zahlung erhalten. Bitte vergessen Sie nicht, dass Sie es innerhalb von 24 Stunden verwenden k\u00f6nnen. Dann nutzen Sie 30% Rabatt f\u00fcr den zweiten Entrichtung eines eingezahlten Plugins. \n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n<div class=\"faq-item\">\n\t\t\t\t\t<div class=\"faq-item-question\">\n\t\t\t\t\t\t<h3 class=\"faq-item-question-text\">Kann ich mein Abonnement f\u00fcr das App, das ich bereits habe, sp\u00e4ter \u00e4ndern?<\/h3>\n\n\t\t\t\t\t\t<div class=\"faq-item-question-icon\"><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"faq-item-answer\">\n\t\t\t\t\t\t<div class=\"faq-item-answer-text\">\n\nJa! Sie k\u00f6nnen das Tarif jederzeit \u00e4ndern oder k\u00fcndigen. Die Summe eingezahlt f\u00fcr bisherig Tarif wird zu einem neuen Tarif nachgerechnet. \n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n<div class=\"faq-item\">\n\t\t\t\t\t<div class=\"faq-item-question\">\n\t\t\t\t\t\t<h3 class=\"faq-item-question-text\">Was bedeutet die Beschr\u00e4nkung der App-Views?<\/h3>\n\n\t\t\t\t\t\t<div class=\"faq-item-question-icon\"><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"faq-item-answer\">\n\t\t\t\t\t\t<div class=\"faq-item-answer-text\">\n\nDie Menge der Views zeigt die Menge der Widget-Laden auf Ihrer Seite. Dies zeigtdie Menge der einzelne Besucher auf Ihre Seite mit den Widgets nicht. \nDie Anzahl der Ansichten hat eine monatliche Basis und wird jeden Monat ersetzt und richtet sich nach Ihrem Abonnement. \n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n<div class=\"faq-item\">\n\t\t\t\t\t<div class=\"faq-item-question\">\n\t\t\t\t\t\t<h3 class=\"faq-item-question-text\">Auf wie viele Websites kann ich das Plugin einbinden?<\/h3>\n\n\t\t\t\t\t\t<div class=\"faq-item-question-icon\"><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"faq-item-answer\">\n\t\t\t\t\t\t<div class=\"faq-item-answer-text\">\n\nWenn Sie einen kostenlosen Plan haben, k\u00f6nnen Sie das Widget nur auf einer Website generieren. \nIn den gezahlten Abonnements gibt es keine Beschr\u00e4nkungen &#8211; Sie k\u00f6nnen so viele Apps f\u00fcr Ihre Website einbinden wie Sie wollen. \n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n<div class=\"faq-item\">\n\t\t\t\t\t<div class=\"faq-item-question\">\n\t\t\t\t\t\t<h3 class=\"faq-item-question-text\">Kann ich eine kostenlose Installationshilfe von Ihrem Support-Team erhalten?<\/h3>\n\n\t\t\t\t\t\t<div class=\"faq-item-question-icon\"><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"faq-item-answer\">\n\t\t\t\t\t\t<div class=\"faq-item-answer-text\">\n\nJa, Elfsight bietet allen unseren Kunden kostenlosen Support bei der Bildung und Einbetten des Widgets. Elfsight Benutzer k\u00f6nnen Elfsight hochqualifiziertes Hilfeteam erreichen. \n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":0,"parent":2867,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-application-pricing.php","meta":{"publish_to_discourse":"","publish_post_category":"","wpdc_auto_publish_overridden":"","wpdc_topic_tags":"","wpdc_pin_topic":"","wpdc_pin_until":"","discourse_post_id":"","discourse_permalink":"","wpdc_publishing_response":"","wpdc_publishing_error":"","footnotes":""},"class_list":["post-2871","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Click to Call Plugin-Preise (kostenlose und premium)<\/title>\n<meta name=\"description\" content=\"Erstellen Sie Ihr Click to Call Plugin f\u00fcr die Website zum niedrigsten Preis! Die Tarife f\u00fcr das Click to Call Widget reichen von kostenlos bis premium.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elfsight.com\/de\/click-to-call-widget\/pricing\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Click to Call Plugin-Preise (kostenlose und premium)\" \/>\n<meta property=\"og:description\" content=\"Erstellen Sie Ihr Click to Call Plugin f\u00fcr die Website zum niedrigsten Preis! Die Tarife f\u00fcr das Click to Call Widget reichen von kostenlos bis premium.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elfsight.com\/de\/click-to-call-widget\/pricing\/\" \/>\n<meta property=\"og:site_name\" content=\"Elfsight DE\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-21T09:18:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Click to Call Plugin-Preise (kostenlose und premium)","description":"Erstellen Sie Ihr Click to Call Plugin f\u00fcr die Website zum niedrigsten Preis! Die Tarife f\u00fcr das Click to Call Widget reichen von kostenlos bis premium.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elfsight.com\/de\/click-to-call-widget\/pricing\/","og_locale":"de_DE","og_type":"article","og_title":"Click to Call Plugin-Preise (kostenlose und premium)","og_description":"Erstellen Sie Ihr Click to Call Plugin f\u00fcr die Website zum niedrigsten Preis! Die Tarife f\u00fcr das Click to Call Widget reichen von kostenlos bis premium.","og_url":"https:\/\/elfsight.com\/de\/click-to-call-widget\/pricing\/","og_site_name":"Elfsight DE","article_modified_time":"2022-03-21T09:18:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elfsight.com\/de\/click-to-call-widget\/pricing\/","url":"https:\/\/elfsight.com\/de\/click-to-call-widget\/pricing\/","name":"Click to Call Plugin-Preise (kostenlose und premium)","isPartOf":{"@id":"https:\/\/elfsight.com\/de\/#website"},"datePublished":"2020-09-15T08:29:01+00:00","dateModified":"2022-03-21T09:18:37+00:00","description":"Erstellen Sie Ihr Click to Call Plugin f\u00fcr die Website zum niedrigsten Preis! Die Tarife f\u00fcr das Click to Call Widget reichen von kostenlos bis premium.","breadcrumb":{"@id":"https:\/\/elfsight.com\/de\/click-to-call-widget\/pricing\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elfsight.com\/de\/click-to-call-widget\/pricing\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/elfsight.com\/de\/click-to-call-widget\/pricing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elfsight.com\/de\/"},{"@type":"ListItem","position":2,"name":"Click to Call","item":"https:\/\/elfsight.com\/de\/click-to-call-widget\/"},{"@type":"ListItem","position":3,"name":"Click to Call &#8211; Pricing"}]},{"@type":"WebSite","@id":"https:\/\/elfsight.com\/de\/#website","url":"https:\/\/elfsight.com\/de\/","name":"Elfsight DE","description":"Just another Elfsight Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elfsight.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"meta_box":{"industry":"","seo_heading":"","heading":"","description":"","cta_heading":"","cta_description":"","application":"490","h1":"Preise f\u00fcr Click to Call Widget","h1_caption":"14 Tage Geld-zur\u00fcck-Garantie. Ohne Risiko k\u00f6nnen Sie jederzeit k\u00fcndigen.","application_category":[],"applications_title":"","applications_request_title":"","applications_request_button_text":"","hero_text":"","hero_video":"","hero_video_schema_markup":"","selling_points_title":"","selling_points_caption":"","selling_points":[],"selling_points_cta_text":"","features_title":"","features":"","ed_cta_examples_text":"","ed_cta_examples_hidden":"","ed_cta_demo_text":"","ed_cta_demo_hidden":"","why_caption":"","why_editor_title":"","why_editor_text":"","why_team_title":"","why_team_text":"","why_service_title":"","why_service_text":"","template_catalog_visible":"","template_catalog_title":"","template_catalog_text":"","template_catalog_categories_visible":"","demo_title":"","demo_caption":"","default_faq_hidden":"1","app_template_category":[],"platform":"","template_public_id":"","codecanyon_url":"","codecanyon_item_id":"","codecanyon_price":"","pricing_caption":"","pricing_elfsight_apps_hide_column":"","pricing_elfsight_apps_url":"","pricing_codecanyon_price_caption":"","integration_category":[],"integration_request_title":"","integration_request_cta":"","integration_platform":"","integrations":[],"platform_category":[],"video_schema_markup":"","price":"","trial":"","benefits":[],"button_url":"","button_target_blank":"","button_nofollow":"","attributes":[],"tags":[],"tags_disable_links":"","hide_more_platforms":"","video_object":"","demo_hide_cta":"","demo_hide_cloud_options":"","pricing_title":"","pricing":[],"related_apps_title":"","related_apps_hidden":"","author":"","image":[],"title":"","job":"","social_networks":[]},"_links":{"self":[{"href":"https:\/\/elfsight.com\/de\/wp-json\/wp\/v2\/pages\/2871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elfsight.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/elfsight.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/elfsight.com\/de\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/elfsight.com\/de\/wp-json\/wp\/v2\/comments?post=2871"}],"version-history":[{"count":4,"href":"https:\/\/elfsight.com\/de\/wp-json\/wp\/v2\/pages\/2871\/revisions"}],"predecessor-version":[{"id":6988,"href":"https:\/\/elfsight.com\/de\/wp-json\/wp\/v2\/pages\/2871\/revisions\/6988"}],"up":[{"embeddable":true,"href":"https:\/\/elfsight.com\/de\/wp-json\/wp\/v2\/pages\/2867"}],"wp:attachment":[{"href":"https:\/\/elfsight.com\/de\/wp-json\/wp\/v2\/media?parent=2871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}