{"id":2468,"date":"2020-09-02T12:49:21","date_gmt":"2020-09-02T12:49:21","guid":{"rendered":"https:\/\/elfsight.com\/de\/?page_id=2468"},"modified":"2020-10-13T15:18:28","modified_gmt":"2020-10-13T15:18:28","slug":"features","status":"publish","type":"page","link":"https:\/\/elfsight.com\/de\/back-to-top-widget\/features\/","title":{"rendered":"Back to Top &#8211; Features"},"content":{"rendered":"\n<section class=\"application-features-group section\" id=\"CONTROL\">\n                    <div class=\"inner\">\n                        <div class=\"col-row\">\n                            <div class=\"col-6 col-offset-3 col-m-12 col-m-offset-0\">\n\n<h3>Scroll-Position und Scroll-Geschwindigkeit <\/h3>\n<p>Die Taste wird m\u00f6glicherweise direkt angezeigt, nachdem der Benutzer die Seite an die definierte Position gescrollt hat. Sie k\u00f6nnen die Position in Prozent bestimmen und die Scroll-Geschwindigkeit eingerichtet, um Benutzererfahrung in einem Klick zu verbessern.<\/p>\n\n<h3>Zeigen Sie das Widget auf beliebigen Seiten an<\/h3>\n<p>Demonstrieren Sie die Nach oben Taste auf allen Seiten Ihrer Website oder w\u00e4hlen Sie diejenigen aus, die viel Inhalt enthalten. Sie k\u00f6nnen die Seiten auch ausschlie\u00dfen, sodass die Schaltfl\u00e4che auf jeder Website-Seite angezeigt wird, mit Ausnahme derjenigen, die Sie als ausgeschlossene markiert haben.<\/p>\n\n<h3>Ger\u00e4te<\/h3>\n<p>Das Plugin Nach oben ist mit jedem Ger\u00e4t kompatibel &#8211; vom Desktop bis Smartphone. Sie m\u00fcssen sich also keine Sorgen um Ihr mobiles Publikum machen &#8211; es kann Ihre praktischen Navigationsoptionen zusammen mit den Desktop-Benutzern nutzen.<\/p>\n\n<\/div>\n                        <\/div>\n                    <\/div>\n\n                    <div class=\"application-features-group-title\">Kontrolle<\/div>\n                <\/section>\n<section class=\"application-features-group section\" id=\"POSITION\">\n                    <div class=\"inner\">\n                        <div class=\"col-row\">\n                            <div class=\"col-6 col-offset-3 col-m-12 col-m-offset-0\">\n\n<h3>Positionsoptionen<\/h3>\n<p>Sie k\u00f6nnen den Tastentyp ausw\u00e4hlen &#8211; es kann schwebend oder eingebettet sein. Begleiten Sie den Benutzer mit dem schwebenden Taste durch das Scrollen Ihrer Website. Der schwebende Taste verf\u00fcgt \u00fcber 8 Positionen. Die eingebettete Taste Scrollen eignet sich perfekt f\u00fcr die Einf\u00fchrung in die Inhaltszone Ihrer Website.<\/p>\n\n<h3>Versatz<\/h3>\n<p>Markieren Sie den Versatz in Pixel, damit Sie die Schaltfl\u00e4che f\u00fcr Ihr Publikum gut sichtbar oder nicht erkennbar machen k\u00f6nnen. Was auch immer Ihre Wahl ist, k\u00f6nnen Sie sicher sein, Ihre Benutzer leicht nach oben auf der Seite zur\u00fcckkehren.<\/p>\n\n<h3>Layout<\/h3>\n<p>Sie k\u00f6nnen eine horizontale oder vertikale Taste erstellen. Mit diesen beiden Optionen k\u00f6nnen Sie eine Taste erstellen, die perfekt zu Ihrem Website-Design passt.<\/p>\n<\/div>\n                        <\/div>\n                    <\/div>\n\n                    <div class=\"application-features-group-title\">POSITION<\/div>\n                <\/section>\n<section class=\"application-cta-ed\">\n                    <div class=\"inner\">\n                        <div class=\"col-row\">\n                            <div class=\"col-6 col-m-12\">\n                                <div class=\"application-cta-ed-item-examples application-cta-ed-item\">\n                                    <div class=\"application-cta-ed-item-icon\">\n                                        <svg viewBox=\"0 0 25 25\" width=\"100%\" height=\"100%\">\n                                            <use xlink:href=\"#icon-desktop\"><\/use>\n                                        <\/svg>\n                                    <\/div>\n\n                                    <div class=\"application-cta-ed-item-content\">\n                                        <div class=\"application-cta-ed-item-content-title\">Anwendungsbeispiele<\/div>\n\n                                        <div class=\"application-cta-ed-item-content-text\">Sehen Sie echte Beispiele an, um das volle Potenzial von  f\u00fcr Ihre Website zu entdecken.\n                                        <\/div>\n\n                                        <a class=\"button-48 button-purple button\" href=\"\">In Aktion sehen<\/a>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                            <div class=\"col-6 col-m-12\">\n                                <div class=\"application-cta-ed-item-demo application-cta-ed-item\">\n                                    <div class=\"application-cta-ed-item-icon\">\n                                        <svg viewBox=\"0 0 25 25\" width=\"100%\" height=\"100%\">\n                                            <use xlink:href=\"#icon-settings\"><\/use>\n                                        <\/svg>\n                                    <\/div>\n\n                                    <div class=\"application-cta-ed-item-content\">\n                                        <div class=\"application-cta-ed-item-content-title\">Live-Demo<\/div>\n\n                                        <div class=\"application-cta-ed-item-content-text\">Probieren Sie alle Funktionen von  in Live-Demo aus. Keine Zahlung, Keine Registration. Keine Codierung.\n                                        <\/div>\n\n                                        <a class=\"button-48 button-magenta button\" href=\"#demo\" data-nav-scroll-to=\"demo\">Jetzt testen<\/a>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/section>\n\n<section class=\"application-features-group section\" id=\"STYLE\">\n                    <div class=\"inner\">\n                        <div class=\"col-row\">\n                            <div class=\"col-6 col-offset-3 col-m-12 col-m-offset-0\">\n\n<h3>\u00c4ndern Sie die Gr\u00f6\u00dfe<\/h3>\n<p>Sie k\u00f6nnen kleine, mittlere oder gro\u00dfe Taste erstellen. Z\u00f6gern Sie nicht &#8211; unabh\u00e4ngig von Ihrer Wahl passt die Schaltfl\u00e4che perfekt zum gesamten Design der Website. Die Gr\u00f6\u00dfe kann jederzeit ge\u00e4ndert werden.\n<\/p>\n\n<h3>W\u00e4hlen Sie die Form und Grenze<\/h3>\n<p>Es gibt drei Formvarianten &#8211; Ihre Taste kann quadratisch, rund oder kreisf\u00f6rmig sein. Jede Taste kann eine kontrastierende Grenze enth\u00e4lt, um es auf der Seite sichtbar. Die Grenze kann leicht mit einem Klick abgeschaltet werden.\n<\/p>\n\n<h3>W\u00e4hlen Sie die Schriftgr\u00f6\u00dfe<\/h3>\n<p>Jede Taste wird durch Text begleitet. Sie sind frei, es fett zu machen, um die Schaltfl\u00e4che auf den Seiten Ihrer Website zu markieren. Oder machen Sie den Text normal und w\u00e4hlen Sie andere M\u00f6glichkeiten, um die Aufmerksamkeit der Benutzer auf darauf zu ziehen.<\/p>\n\n<h3>F\u00e4rben Sie die Tasten neu<\/h3>\n<p>Nach oben Widget ist extrem anpassbar. Sie k\u00f6nnen die Schaltfl\u00e4che selbst, den Text und das Symbol neu einf\u00e4rben und die Rahmenfarbe ausw\u00e4hlen. Erstellen Sie eine kontraste Taste oder machen es wie eine Funktion nativ aussehen &#8211; es ist an Ihnen zu entscheiden!<\/p>\n\n<\/div>\n                        <\/div>\n                    <\/div>\n\n                    <div class=\"application-features-group-title\">STIL<\/div>\n                <\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":0,"parent":2467,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-application-features.php","meta":{"publish_to_discourse":"","publish_post_category":"","wpdc_auto_publish_overridden":"","wpdc_topic_tags":"","wpdc_pin_topic":"","wpdc_pin_until":"","discourse_post_id":"","discourse_permalink":"","wpdc_publishing_response":"","wpdc_publishing_error":"","footnotes":""},"class_list":["post-2468","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Responsive Zur\u00fcck zum Anfang - 20+ benutzerdefinierte Einstellungen<\/title>\n<meta name=\"description\" content=\"Testen Sie alle Nach oben Plugin Funktionen in einer Live-Demo. Benutzerdefinierte Einstellungen und gebrauchsfertige Vorlagen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elfsight.com\/de\/back-to-top-widget\/features\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Responsive Zur\u00fcck zum Anfang - 20+ benutzerdefinierte Einstellungen\" \/>\n<meta property=\"og:description\" content=\"Testen Sie alle Nach oben Plugin Funktionen in einer Live-Demo. Benutzerdefinierte Einstellungen und gebrauchsfertige Vorlagen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elfsight.com\/de\/back-to-top-widget\/features\/\" \/>\n<meta property=\"og:site_name\" content=\"Elfsight DE\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-13T15:18:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Responsive Zur\u00fcck zum Anfang - 20+ benutzerdefinierte Einstellungen","description":"Testen Sie alle Nach oben Plugin Funktionen in einer Live-Demo. Benutzerdefinierte Einstellungen und gebrauchsfertige Vorlagen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elfsight.com\/de\/back-to-top-widget\/features\/","og_locale":"de_DE","og_type":"article","og_title":"Responsive Zur\u00fcck zum Anfang - 20+ benutzerdefinierte Einstellungen","og_description":"Testen Sie alle Nach oben Plugin Funktionen in einer Live-Demo. Benutzerdefinierte Einstellungen und gebrauchsfertige Vorlagen.","og_url":"https:\/\/elfsight.com\/de\/back-to-top-widget\/features\/","og_site_name":"Elfsight DE","article_modified_time":"2020-10-13T15:18:28+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elfsight.com\/de\/back-to-top-widget\/features\/","url":"https:\/\/elfsight.com\/de\/back-to-top-widget\/features\/","name":"Responsive Zur\u00fcck zum Anfang - 20+ benutzerdefinierte Einstellungen","isPartOf":{"@id":"https:\/\/elfsight.com\/de\/#website"},"datePublished":"2020-09-02T12:49:21+00:00","dateModified":"2020-10-13T15:18:28+00:00","description":"Testen Sie alle Nach oben Plugin Funktionen in einer Live-Demo. Benutzerdefinierte Einstellungen und gebrauchsfertige Vorlagen.","breadcrumb":{"@id":"https:\/\/elfsight.com\/de\/back-to-top-widget\/features\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elfsight.com\/de\/back-to-top-widget\/features\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/elfsight.com\/de\/back-to-top-widget\/features\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elfsight.com\/de\/"},{"@type":"ListItem","position":2,"name":"Back to Top","item":"https:\/\/elfsight.com\/de\/back-to-top-widget\/"},{"@type":"ListItem","position":3,"name":"Back to Top &#8211; Features"}]},{"@type":"WebSite","@id":"https:\/\/elfsight.com\/de\/#website","url":"https:\/\/elfsight.com\/de\/","name":"Elfsight DE","description":"Just another Elfsight Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elfsight.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"meta_box":{"industry":"","seo_heading":"","heading":"","description":"","cta_heading":"","cta_description":"","application":"511","h1":"Funktionen des Back to Top Plugins","h1_caption":"Sehen Sie sich alle Funktionen der Zur\u00fcck zum Anfang Plugin an und erfahren Sie, wie Sie das effektivste Widget erstellen k\u00f6nnen","application_category":[],"applications_title":"","applications_request_title":"","applications_request_button_text":"","hero_text":"","hero_video":"","hero_video_schema_markup":"","selling_points_title":"","selling_points_caption":"","selling_points":[],"selling_points_cta_text":"","features_title":"","features":"","ed_cta_examples_text":"","ed_cta_examples_hidden":"","ed_cta_demo_text":"","ed_cta_demo_hidden":"","why_caption":"","why_editor_title":"","why_editor_text":"","why_team_title":"","why_team_text":"","why_service_title":"","why_service_text":"","template_catalog_visible":"","template_catalog_title":"","template_catalog_text":"","template_catalog_categories_visible":"","demo_title":"","demo_caption":"","default_faq_hidden":"","app_template_category":[],"platform":"","template_public_id":"","codecanyon_url":"","codecanyon_item_id":"","codecanyon_price":"","pricing_caption":"","pricing_elfsight_apps_hide_column":"","pricing_elfsight_apps_url":"","pricing_codecanyon_price_caption":"","integration_category":[],"integration_request_title":"","integration_request_cta":"","integration_platform":"","integrations":[],"platform_category":[],"video_schema_markup":"","price":"","trial":"","benefits":[],"button_url":"","button_target_blank":"","button_nofollow":"","attributes":[],"tags":[],"tags_disable_links":"","hide_more_platforms":"","video_object":"","demo_hide_cta":"","demo_hide_cloud_options":"","pricing_title":"","pricing":[],"related_apps_title":"","related_apps_hidden":"","author":"","image":[],"title":"","job":"","social_networks":[]},"_links":{"self":[{"href":"https:\/\/elfsight.com\/de\/wp-json\/wp\/v2\/pages\/2468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elfsight.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/elfsight.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/elfsight.com\/de\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/elfsight.com\/de\/wp-json\/wp\/v2\/comments?post=2468"}],"version-history":[{"count":7,"href":"https:\/\/elfsight.com\/de\/wp-json\/wp\/v2\/pages\/2468\/revisions"}],"predecessor-version":[{"id":2486,"href":"https:\/\/elfsight.com\/de\/wp-json\/wp\/v2\/pages\/2468\/revisions\/2486"}],"up":[{"embeddable":true,"href":"https:\/\/elfsight.com\/de\/wp-json\/wp\/v2\/pages\/2467"}],"wp:attachment":[{"href":"https:\/\/elfsight.com\/de\/wp-json\/wp\/v2\/media?parent=2468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}