{"id":22578,"date":"2024-10-11T04:20:51","date_gmt":"2024-10-11T04:20:51","guid":{"rendered":"https:\/\/elfsight.com\/de\/?page_id=22578"},"modified":"2024-10-16T07:01:25","modified_gmt":"2024-10-16T07:01:25","slug":"pricing","status":"publish","type":"page","link":"https:\/\/elfsight.com\/de\/calculator-form-widget\/pricing\/","title":{"rendered":"Calculator &#8211; Pricing"},"content":{"rendered":"<div class=\"faq\" data-component=\"FAQ\"><br \/>\n<div class=\"faq-item\">\r\n\t\t\t\t\t<div class=\"faq-item-question\">\r\n\t\t\t\t\t\t<h3 class=\"faq-item-question-text\">Kann ich eine R\u00fcckerstattung erhalten, wenn ich es mir anders \u00fcberlege?<\/h3>\r\n\r\n\t\t\t\t\t\t<div class=\"faq-item-question-icon\"><\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"faq-item-answer\">\r\n\t\t\t\t\t\t<div class=\"faq-item-answer-text\"><br \/>\nJa, Sie k\u00f6nnen aus beliebigem Grund innerhalb von 14 Tagen eine vollst\u00e4ndige R\u00fcckerstattung erhalten.<br \/>\n<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><br \/>\n<div class=\"faq-item\">\r\n\t\t\t\t\t<div class=\"faq-item-question\">\r\n\t\t\t\t\t\t<h3 class=\"faq-item-question-text\">Kann ich mein Abonnement jederzeit k\u00fcndigen?<\/h3>\r\n\r\n\t\t\t\t\t\t<div class=\"faq-item-question-icon\"><\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"faq-item-answer\">\r\n\t\t\t\t\t\t<div class=\"faq-item-answer-text\"><br \/>\nJa, Sie k\u00f6nnen Ihr Abonnement jederzeit eigenst\u00e4ndig in Ihrem Elfsight-Konto k\u00fcndigen.<br \/>\n<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><br \/>\n<div class=\"faq-item\">\r\n\t\t\t\t\t<div class=\"faq-item-question\">\r\n\t\t\t\t\t\t<h3 class=\"faq-item-question-text\">Kann ich 20 % auf die Abonnementkosten sparen?<\/h3>\r\n\r\n\t\t\t\t\t\t<div class=\"faq-item-question-icon\"><\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"faq-item-answer\">\r\n\t\t\t\t\t\t<div class=\"faq-item-answer-text\"><br \/>\nJa, innerhalb von 24 Stunden nach Ihrer Anmeldung erhalten Sie einen Willkommensgutschein mit 20 % Rabatt. Verwenden Sie den Gutschein rechtzeitig!<br \/>\n<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><br \/>\n<div class=\"faq-item\">\r\n\t\t\t\t\t<div class=\"faq-item-question\">\r\n\t\t\t\t\t\t<h3 class=\"faq-item-question-text\">K\u00f6nnen Sie mir bei der Installation des Widgets auf meiner Website helfen?<\/h3>\r\n\r\n\t\t\t\t\t\t<div class=\"faq-item-question-icon\"><\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"faq-item-answer\">\r\n\t\t\t\t\t\t<div class=\"faq-item-answer-text\"><br \/>\nJa, mit unseren kostenpflichtigen Tarifen bieten wir kostenlose Installationshilfe an. Erstellen Sie ein Widget, abonnieren Sie einen kostenpflichtigen Tarif und senden Sie dem Support eine Nachricht mit Ihren Anforderungen. Wir helfen Ihnen so schnell und effizient wie m\u00f6glich.<br \/>\n<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><br \/>\n<div class=\"faq-item\">\r\n\t\t\t\t\t<div class=\"faq-item-question\">\r\n\t\t\t\t\t\t<h3 class=\"faq-item-question-text\">Brauche ich eine Kreditkarte, um mich anzumelden?<\/h3>\r\n\r\n\t\t\t\t\t\t<div class=\"faq-item-question-icon\"><\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"faq-item-answer\">\r\n\t\t\t\t\t\t<div class=\"faq-item-answer-text\"><br \/>\nNein, eine Kreditkarte ist f\u00fcr die Registrierung nicht erforderlich. Sie k\u00f6nnen v\u00f6llig kostenlos starten, ohne zus\u00e4tzliche Bedingungen.<br \/>\n<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><br \/>\n<div class=\"faq-item\">\r\n\t\t\t\t\t<div class=\"faq-item-question\">\r\n\t\t\t\t\t\t<h3 class=\"faq-item-question-text\">Kann ich ein Widget erstellen, ohne mich f\u00fcr Ihren Dienst anzumelden?<\/h3>\r\n\r\n\t\t\t\t\t\t<div class=\"faq-item-question-icon\"><\/div>\r\n\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"faq-item-answer\">\r\n\t\t\t\t\t\t<div class=\"faq-item-answer-text\"><br \/>\nJa, Sie k\u00f6nnen im Demo-Modus ein Widget erstellen, ohne sich anzumelden. Um jedoch den Installationscode zu erhalten und es auf Ihrer Website hinzuzuf\u00fcgen, m\u00fcssen Sie sich registrieren.<br \/>\n<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div><br \/>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":28,"featured_media":0,"parent":22566,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/template-application-pricing.php","meta":{"publish_to_discourse":"","publish_post_category":"","wpdc_auto_publish_overridden":"","wpdc_topic_tags":"","wpdc_pin_topic":"","wpdc_pin_until":"","discourse_post_id":"","discourse_permalink":"","wpdc_publishing_response":"","wpdc_publishing_error":"","footnotes":""},"class_list":["post-22578","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rechner-Widget kostenlos oder mit Premium-Tarifpl\u00e4nen<\/title>\n<meta name=\"description\" content=\"F\u00fcgen Sie ein Rechner-Widget kostenlos oder mit einem unserer g\u00fcnstigen und erschwinglichen Premium-Tarifpl\u00e4ne zu jeder Website hinzu\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elfsight.com\/de\/calculator-form-widget\/pricing\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rechner-Widget kostenlos oder mit Premium-Tarifpl\u00e4nen\" \/>\n<meta property=\"og:description\" content=\"F\u00fcgen Sie ein Rechner-Widget kostenlos oder mit einem unserer g\u00fcnstigen und erschwinglichen Premium-Tarifpl\u00e4ne zu jeder Website hinzu\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elfsight.com\/de\/calculator-form-widget\/pricing\/\" \/>\n<meta property=\"og:site_name\" content=\"Elfsight DE\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-16T07:01:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rechner-Widget kostenlos oder mit Premium-Tarifpl\u00e4nen","description":"F\u00fcgen Sie ein Rechner-Widget kostenlos oder mit einem unserer g\u00fcnstigen und erschwinglichen Premium-Tarifpl\u00e4ne zu jeder Website hinzu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elfsight.com\/de\/calculator-form-widget\/pricing\/","og_locale":"de_DE","og_type":"article","og_title":"Rechner-Widget kostenlos oder mit Premium-Tarifpl\u00e4nen","og_description":"F\u00fcgen Sie ein Rechner-Widget kostenlos oder mit einem unserer g\u00fcnstigen und erschwinglichen Premium-Tarifpl\u00e4ne zu jeder Website hinzu","og_url":"https:\/\/elfsight.com\/de\/calculator-form-widget\/pricing\/","og_site_name":"Elfsight DE","article_modified_time":"2024-10-16T07:01:25+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elfsight.com\/de\/calculator-form-widget\/pricing\/","url":"https:\/\/elfsight.com\/de\/calculator-form-widget\/pricing\/","name":"Rechner-Widget kostenlos oder mit Premium-Tarifpl\u00e4nen","isPartOf":{"@id":"https:\/\/elfsight.com\/de\/#website"},"datePublished":"2024-10-11T04:20:51+00:00","dateModified":"2024-10-16T07:01:25+00:00","description":"F\u00fcgen Sie ein Rechner-Widget kostenlos oder mit einem unserer g\u00fcnstigen und erschwinglichen Premium-Tarifpl\u00e4ne zu jeder Website hinzu","breadcrumb":{"@id":"https:\/\/elfsight.com\/de\/calculator-form-widget\/pricing\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elfsight.com\/de\/calculator-form-widget\/pricing\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/elfsight.com\/de\/calculator-form-widget\/pricing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elfsight.com\/de\/"},{"@type":"ListItem","position":2,"name":"Calculator","item":"https:\/\/elfsight.com\/de\/calculator-form-widget\/"},{"@type":"ListItem","position":3,"name":"Calculator &#8211; Pricing"}]},{"@type":"WebSite","@id":"https:\/\/elfsight.com\/de\/#website","url":"https:\/\/elfsight.com\/de\/","name":"Elfsight DE","description":"Just another Elfsight Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elfsight.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"meta_box":{"industry":"","seo_heading":"","heading":"","description":"","cta_heading":"","cta_description":"","application":"22559","h1":"","h1_caption":"","application_category":[],"applications_title":"","applications_request_title":"","applications_request_button_text":"","hero_text":"","hero_video":"","hero_video_schema_markup":"","selling_points_title":"","selling_points_caption":"","selling_points":[],"selling_points_cta_text":"","features_title":"","features":"","ed_cta_examples_text":"","ed_cta_examples_hidden":"","ed_cta_demo_text":"","ed_cta_demo_hidden":"","why_caption":"","why_editor_title":"","why_editor_text":"","why_team_title":"","why_team_text":"","why_service_title":"","why_service_text":"","template_catalog_visible":"","template_catalog_title":"","template_catalog_text":"","template_catalog_categories_visible":"","demo_title":"","demo_caption":"","default_faq_hidden":"1","app_template_category":[],"platform":"","template_public_id":"","codecanyon_url":"","codecanyon_item_id":"","codecanyon_price":"","pricing_caption":"","pricing_elfsight_apps_hide_column":"","pricing_elfsight_apps_url":"","pricing_codecanyon_price_caption":"","integration_category":[],"integration_request_title":"","integration_request_cta":"","integration_platform":"","integrations":[],"platform_category":[],"video_schema_markup":"","price":"","trial":"","benefits":[],"button_url":"","button_target_blank":"","button_nofollow":"","attributes":[],"tags":[],"tags_disable_links":"","hide_more_platforms":"","video_object":"","demo_hide_cta":"","demo_hide_cloud_options":"","pricing_title":"","pricing":[],"related_apps_title":"","related_apps_hidden":"","author":"","image":[],"title":"","job":"","social_networks":[]},"_links":{"self":[{"href":"https:\/\/elfsight.com\/de\/wp-json\/wp\/v2\/pages\/22578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elfsight.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/elfsight.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/elfsight.com\/de\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/elfsight.com\/de\/wp-json\/wp\/v2\/comments?post=22578"}],"version-history":[{"count":2,"href":"https:\/\/elfsight.com\/de\/wp-json\/wp\/v2\/pages\/22578\/revisions"}],"predecessor-version":[{"id":22584,"href":"https:\/\/elfsight.com\/de\/wp-json\/wp\/v2\/pages\/22578\/revisions\/22584"}],"up":[{"embeddable":true,"href":"https:\/\/elfsight.com\/de\/wp-json\/wp\/v2\/pages\/22566"}],"wp:attachment":[{"href":"https:\/\/elfsight.com\/de\/wp-json\/wp\/v2\/media?parent=22578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}